{"id":2769,"date":"2022-11-11T10:57:28","date_gmt":"2022-11-11T08:57:28","guid":{"rendered":"https:\/\/sfentoni-cave.com\/die-hohle\/"},"modified":"2025-01-15T13:48:43","modified_gmt":"2025-01-15T11:48:43","slug":"die-hohle","status":"publish","type":"page","link":"https:\/\/sfentoni-cave.com\/de\/die-hohle\/","title":{"rendered":"Die H\u00f6hle"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2769\" class=\"elementor elementor-2769 elementor-81\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d22056 e-con-full e-flex e-con e-parent\" data-id=\"3d22056\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-fb9a25b e-con-full e-flex e-con e-child\" data-id=\"fb9a25b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-4cb9c3e e-flex e-con-boxed e-con e-child\" data-id=\"4cb9c3e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-68578db elementor-widget elementor-widget-heading\" data-id=\"68578db\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Geschichten, Mythen und Geologie<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e99dd19 elementor-widget elementor-widget-heading\" data-id=\"e99dd19\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Die H\u00f6hle<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-80e9973 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"80e9973\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Sfendoni-H\u00f6hle am Fu\u00dfe des Psiloritis ist eine der gr\u00f6\u00dften nat\u00fcrlichen Architektursch\u00f6pfungen in Griechenland. In ihrem Inneren finden Sie Stalagmiten und Stalaktiten, die im Laufe der Jahre durch den Wasserfluss entstanden sind. Wenn Sie die H\u00f6hle besuchen, werden Sie die atemberaubende nat\u00fcrliche Sch\u00f6nheit Kretas entdecken. Sie ist vom Dorf Zoniana aus leicht zu erreichen.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a95f827 e-n-tabs-mobile elementor-widget elementor-widget-n-tabs\" data-id=\"a95f827\" data-element_type=\"widget\" data-settings=\"{&quot;horizontal_scroll&quot;:&quot;disable&quot;}\" data-widget_type=\"nested-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-tabs\" data-widget-number=\"177600551\" aria-label=\"Tabs. Open items with Enter or Space, close with Escape and navigate using the Arrow keys.\">\n\t\t\t<div class=\"e-n-tabs-heading\" role=\"tablist\">\n\t\t\t\t\t<button id=\"e-n-tab-title-1776005511\" class=\"e-n-tab-title\" aria-selected=\"true\" data-tab-index=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-n-tab-content-1776005511\" style=\"--n-tabs-title-order: 1;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tGeschichte\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-1776005512\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1776005512\" style=\"--n-tabs-title-order: 2;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tMythos\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"e-n-tabs-content\">\n\t\t\t\t<div id=\"e-n-tab-content-1776005511\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1776005511\" data-tab-index=\"1\" style=\"--n-tabs-title-order: 1;\" class=\"e-active elementor-element elementor-element-f0d4cbe e-flex e-con-boxed e-con e-parent\" data-id=\"f0d4cbe\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cfe33f3 elementor-widget elementor-widget-heading\" data-id=\"cfe33f3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Die Geschichte der H\u00f6hle<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-673afcd e-flex e-con-boxed e-con e-child\" data-id=\"673afcd\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-91d1686 e-con-full e-flex e-con e-child\" data-id=\"91d1686\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b43efa8 elementor-widget elementor-widget-text-editor\" data-id=\"b43efa8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die H\u00f6hle ist den Einheimischen schon lange bekannt. In schwierigen Zeiten war sie ein <strong>Zufluchtsort<\/strong> und ein rettender Ort f\u00fcr Verfolgte und Rebellen (im kretischen Dialekt \u201ehainides\u201c).<\/p>\n<p>Vor ein paar Jahrzehnten wurde ein <strong>jugendliches Skelett<\/strong> disartikuliert gefunden. Das Skelett war au\u00dferhalb der letzten Kammer, in der &#8222;Kammer des verlorenen Kindes&#8220;, wie sie sp\u00e4ter genannt wurde, mit Stalagmiten bedeckt. Es wird gemunkelt, dass das Skelett zu dem von Sfenton get\u00f6teten Jungen geh\u00f6rt oder zu einem Kind, dessen Neugier und Faszination f\u00fcr das Unbekannte es in die H\u00f6hle f\u00fchrte und das, nachdem es mehrere Stunden durch die labyrinthischen G\u00e4nge gewandert war, den Eingang verlor, ohne ihn je zu finden und dort starb. Niemand kann diesen Tod mit Gewissheit aufkl\u00e4ren.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-880a735 e-con-full e-flex e-con e-child\" data-id=\"880a735\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ae4060 elementor-widget elementor-widget-text-editor\" data-id=\"3ae4060\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wie durch arch\u00e4ologische Ausgrabungen nachgewiesen wurde, war die H\u00f6hle schon viel fr\u00fcher bewohnt. Bei den Ausgrabungen, die im Januar 1987 von E. Gavrilakis im Auftrag des \u00f6rtlichen Arch\u00e4ologischen Amtes in der H\u00f6hle durchgef\u00fchrt wurden, wurden menschliche Siedlungen aus der <strong>fr\u00fchminoischen Periode (3500 &#8211; 2300\/2150 v. Chr.)<\/strong>, aber auch Material aus der <strong>sp\u00e4tr\u00f6mischen Periode<\/strong> gefunden. Es wurden 95 Tierknochen von Hauss\u00e4ugetieren (L\u00e4mmer, Ziegen, Schweine) und Wilds\u00e4ugetieren (Hirsche) gefunden.<\/p>\n<p>Schlie\u00dflich ist die H\u00f6hle Teil des <strong>Naturparks Psiloritis<\/strong>, der zum Netz der Europ\u00e4ischen Geoparks geh\u00f6rt, einem Netz von Schutzgebieten mit besonderem geologischen Erbe <strong>unter der Schirmherrschaft der UNESCO.<\/strong><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-1776005512\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1776005512\" data-tab-index=\"2\" style=\"--n-tabs-title-order: 2;\" class=\" elementor-element elementor-element-9652099 e-flex e-con-boxed e-con e-parent\" data-id=\"9652099\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cfa4fde elementor-widget elementor-widget-heading\" data-id=\"cfa4fde\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Der Mythos um die H\u00f6hle<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e6208e5 e-flex e-con-boxed e-con e-child\" data-id=\"e6208e5\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b90e0cb e-con-full e-flex e-con e-child\" data-id=\"b90e0cb\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-674e9c7 elementor-widget elementor-widget-text-editor\" data-id=\"674e9c7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ein bis vor einigen Jahrzehnten unbekannter, jenseitiger und chthonischer Ort, das Loch von Sfendonis. In der dunklen Welt der H\u00f6hle versteckt sich, wer wei\u00df wann, ein sch\u00f6nes, \u00e4therisches Wesen, eine <strong>Fee<\/strong>. Jeden Tag kam sie zu einer bestimmten Stunde aus der H\u00f6hle und ging zur Quelle etwas weiter unten in der Skaffidia, um ein Nickerchen zu machen. Ein Hirte hatte sie viele Male gesehen. Jedes Mal versuchte er, sich ihr zu n\u00e4hern, und jedes Mal verschwand sie in der H\u00f6hle. Aus Lust und Neugierde verfolgte er sie eines Tages. Sobald er sie sah, nahm er seine Stoffschleuder und schlug sie mit einem Stein.<\/p>\n<p>Eine Version der Legende besagt, dass die Fee in der H\u00f6hle verschwand und ein blutiges Tuch am Eingang zur\u00fccklie\u00df. In der anderen Version n\u00e4herte sich der Hirte der verwundeten Fee, fasziniert von ihrer Sch\u00f6nheit, und beugte sich hinunter, um sie zu k\u00fcssen. <\/p><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d266fe1 e-con-full e-flex e-con e-child\" data-id=\"d266fe1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-569125c elementor-widget elementor-widget-text-editor\" data-id=\"569125c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Fee stie\u00df ihn weg und sagte ihm, dass sie ihm<strong>ein seidenes Schilfrohr schenken<\/strong> w\u00fcrde, wenn er ihr nicht weh t\u00e4te<strong>, dass seine Familie und seine Nachkommen es tragen w\u00fcrden, ohne dass es jemals ausgehen w\u00fcrde<\/strong>. Aber der Hirte konnte es nicht ertragen, sie nicht zu k\u00fcssen. Er weinte und die Fee verfluchte ihn, dass seine H\u00e4nde und die H\u00e4nde seiner ganzen Familie zittern w\u00fcrden.<\/p>\n<p><strong>Sfendonis<\/strong><\/p>\n<p>In der Vergangenheit wurde die H\u00f6hle, wenn auch nicht sehr stark, als Versteck genutzt. Das etwas ru\u00dfgeschw\u00e4rzte Dach in der N\u00e4he des Eingangs ist heute der einzige sichtbare Beweis daf\u00fcr. Die Geschichte eines Sfendoni, eines \u201eHaini\u201c aus Sfakia (Rebell), der sich eine Zeit lang in der H\u00f6hle versteckt hielt, ist uns heute m\u00fcndlich \u00fcberliefert. Eines Tages, als Sfentonis Fleisch r\u00f6stete, sah ihn ein junger Mann. Er ging auf ihn zu und bat ihn um etwas zu essen. Aus Wut oder aus Angst, er k\u00f6nnte ihn verraten, trat Haines mit seinem Stivani (Stiefel) so fest auf ihn ein, dass er ihn t\u00f6tete. <strong>Der Name der H\u00f6hle stammt wahrscheinlich von Sfendonis.<\/strong><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0a0d62f e-flex e-con-boxed e-con e-parent\" data-id=\"0a0d62f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-99f1c12 e-flex e-con-boxed e-con e-child\" data-id=\"99f1c12\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-18145dd e-con-full e-flex e-con e-child\" data-id=\"18145dd\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a8dea77 elementor-widget elementor-widget-heading\" data-id=\"a8dea77\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Geologie <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7d6f20 elementor-widget elementor-widget-heading\" data-id=\"b7d6f20\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">und Leben in der H\u00f6hle<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c22431b elementor-widget elementor-widget-text-editor\" data-id=\"c22431b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Gegend au\u00dferhalb der H\u00f6hle ist beeindruckend. Senkrechte, bis zu 50 Meter hohe H\u00e4nge erheben sich wie eine nat\u00fcrliche Wand an der nordwestlichen Seite des Parkplatzes und der Rastpl\u00e4tze. Die massiven, einsamen Felsen, die schwebend dastehen, als h\u00e4tte sie jemand dort hingestellt, dominieren den Ort. In ihren kleinen Spalten versuchen Thymian, Oregano, Astern und andere Pflanzen, mit bewundernswerter Geduld und Ausdauer zu gedeihen.<\/p>\n<p>Kreta ist die Region mit den meisten H\u00f6hlen in Griechenland und hat daher auch die gr\u00f6\u00dfte H\u00f6hlenfauna. Das winzige Troglodyt Isopod Graeconiscus guanophilus wurde bisher nur in der Sfendoni-H\u00f6hle von Zoniana und nirgendwo sonst auf der Welt gefunden. Er ist nicht gr\u00f6\u00dfer als ein Zentimeter, blind und farblos.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a5421ba e-con-full e-flex e-con e-child\" data-id=\"a5421ba\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eb09f31 elementor-hidden-tablet elementor-widget elementor-widget-ucaddon_expanding_content_cards\" data-id=\"eb09f31\" data-element_type=\"widget\" data-widget_type=\"ucaddon_expanding_content_cards.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Expanding Content Cards -->\n\t\t<link id='font-awesome-css' href='https:\/\/sfentoni-cave.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-all.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='font-awesome-4-shim-css' href='https:\/\/sfentoni-cave.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-v4-shims.min.css' type='text\/css' rel='stylesheet' >\n\n<style>\/* widget: Expanding Content Cards *\/\n\n\r\n@keyframes uc_expanding_content_cards_elementor_eb09f31__item-animation {\r\n  0% {\r\n            transform: translateX(50px);\r\n        \t        \tfilter: blur(10px);\r\n\t\t\t\r\n    \t    opacity: 0;\r\n  }\r\n  100% {\r\n            transform: translateX(0px);\r\n        \t            filter: blur(0px);\r\n            \r\n    \t\topacity: 1;\r\n  }\r\n}\r\n\r\n\r\n#uc_expanding_content_cards_elementor_eb09f31 .ue_option{\r\n\topacity:0;\r\n}\r\n\r\n\r\n#uc_expanding_content_cards_elementor_eb09f31 .uc-entrance-animate {\r\n  opacity:1;\r\n}\r\n\r\n#uc_expanding_content_cards_elementor_eb09f31 .uc-entrance-animate {\r\n\tanimation: uc_expanding_content_cards_elementor_eb09f31__item-animation 0.6s cubic-bezier(0.470, 0.000, 0.745, 0.715) both;\r\n}\r\n\r\n\t\t\t\n\n#uc_expanding_content_cards_elementor_eb09f31.exp-wrapper {\n  box-sizing: border-box;\n  display: flex;\n  flex-direction: row;\n  justify-content: center;\n  align-items: center;\n}\n#uc_expanding_content_cards_elementor_eb09f31.exp-wrapper{\n  width:100%;\n}\n#uc_expanding_content_cards_elementor_eb09f31.exp-wrapper .ue_options {\n  display: flex;\n  align-items: center;\n  flex-direction: row;\n  justify-content: center;\n  min-width: 200px;\n  width:100%;\n}\n#uc_expanding_content_cards_elementor_eb09f31.exp-wrapper .ue_options .ue_option {\n  box-sizing: border-box;\n  display: flex;\n  position: relative;\n  overflow: hidden;\n  cursor: pointer;\n  justify-content: center;\n  background-position: center;\n  background-repeat: no-repeat;\n  background-size: cover;\n\n}\n#uc_expanding_content_cards_elementor_eb09f31.exp-wrapper .ue_options .ue_option.active {\n  flex-grow: 10000;\n}\n\n#uc_expanding_content_cards_elementor_eb09f31.exp-wrapper .ue_options .ue_option:not(.active) {\n  justify-content: center;\n}\n#uc_expanding_content_cards_elementor_eb09f31.exp-wrapper .ue_options .ue_option .ue_shadow {\n  position: absolute;\n  bottom: 0px;\n  left: 0px;\n  right: 0px;\n  height: 100%;\n  z-index:1;\n  transition: 800ms;\n}\n#uc_expanding_content_cards_elementor_eb09f31.exp-wrapper .ue_option:not(.active) .ue_label {\n  align-items: center;\n}\n#uc_expanding_content_cards_elementor_eb09f31.exp-wrapper .ue_options .ue_option .ue_label {\n  display: flex;\n  z-index:2;\n  transition: 0.5s cubic-bezier(0.05, 0.61, 0.41, 0.95);\n}\n#uc_expanding_content_cards_elementor_eb09f31.exp-wrapper .ue_options .ue_option.active .ue_label{\n  animation-name: sub-content-fade;\n  animation-duration: 800ms;\n}\n@keyframes sub-content-fade{\n  0%   {opacity:0;}\n  80%  {opacity:0;}\n  100% {opacity:1;}\n}\n\n\n#uc_expanding_content_cards_elementor_eb09f31.exp-wrapper .ue_options .ue_option.active .ue_label .ue_info > div {\n  left: 0px;\n  width:100%;\n}\n#uc_expanding_content_cards_elementor_eb09f31.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_info > div {\n  left: 0px;\n  opacity: 0;\n  width: 0px;\n  height: 0px;\n  transition: width 0ms;\n}\n\n#uc_expanding_content_cards_elementor_eb09f31.exp-wrapper .ue_options .ue_option .ue_label .ue_info > div {\n  position: relative;\n  transition: 0.5s cubic-bezier(0.05, 0.61, 0.41, 0.95), opacity 0.5s ease-out;\n}\n#uc_expanding_content_cards_elementor_eb09f31.exp-wrapper  .ue_options .ue_option .ue_label .ue_info {\n  display: flex;\n  align-items: center;\n  justify-content: center;\n}\n\n#uc_expanding_content_cards_elementor_eb09f31.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_info {\n  margin-left: 0px!important;\n}\n#uc_expanding_content_cards_elementor_eb09f31.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_info .ue_main {\n  opacity: 1;\n  width: auto;\n  height: auto;\n  writing-mode: vertical-rl;\n  text-orientation: mixed;\n  text-decoration: none;\n}\n\n#uc_expanding_content_cards_elementor_eb09f31.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_sub {\n  height:0;\n  margin-top: 0px;\n}\n\n#uc_expanding_content_cards_elementor_eb09f31.exp-wrapper .ue_options .ue_option .ue_label .ue_icon {\n  display: flex;\n  flex-shrink: 0;\n  flex-direction: row;\n  justify-content: center;\n  align-items: center;\n  overflow: hidden;\n  transition: 0.5s;\n}\n\n@media screen and (max-width: 520px) {\n#uc_expanding_content_cards_elementor_eb09f31.exp-wrapper .ue_options {\n  display: grid;\n}\n#uc_expanding_content_cards_elementor_eb09f31.exp-wrapper .ue_options .ue_option{\n    width: 100%;\n}\n#uc_expanding_content_cards_elementor_eb09f31.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_info {\n  margin-left: 0px!important;\n}\n\n#uc_expanding_content_cards_elementor_eb09f31.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_info .ue_main {\n  opacity: 1;\n  width: auto;\n  height: auto;\n  writing-mode: horizontal-tb;\n  text-orientation: mixed;\n  text-decoration: none;\n  transform: rotate(0deg);\n}\n  \n  \n\n#uc_expanding_content_cards_elementor_eb09f31.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_info > div {\n  opacity:1;\n  width:100%;\n  height:auto;\n}\n#uc_expanding_content_cards_elementor_eb09f31.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_sub {\n  height:auto;\n}\n \n}\n\n<\/style>\n\n<div id=\"uc_expanding_content_cards_elementor_eb09f31\" class=\"exp-wrapper  \" data-selectedItem=\"\"  >\n  <div class=\"ue_options uc-items-wrapper\">\n   <div id=\"uc_expanding_content_cards_elementor_eb09f31_item1\" class=\"ue_option elementor-repeater-item-0984f7c  active \" style=\"background-image:url(https:\/\/sfentoni-cave.com\/wp-content\/uploads\/2022\/09\/coming-soon-768x432.jpg);\">\n      <div class=\"ue_shadow\"><\/div>      <div class=\"ue_label\">\n         \n          <div class=\"ue_icon graphic_element_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:xodm=\"http:\/\/www.corel.com\/coreldraw\/odm\/2003\" xml:space=\"preserve\" width=\"1.70666in\" height=\"1.70666in\" style=\"shape-rendering:geometricPrecision; text-rendering:geometricPrecision; image-rendering:optimizeQuality; fill-rule:evenodd; clip-rule:evenodd\" viewBox=\"0 0 1706.66 1706.66\"><defs><style type=\"text\/css\">       .fil1 {fill:#000066}    .fil2 {fill:#DADADA}    .fil0 {fill:#FF6600}     <\/style><\/defs><g id=\"Layer_x0020_1\"><metadata id=\"CorelCorpID_0Corel-Layer\"><\/metadata><path class=\"fil0\" d=\"M1124.97 1325.21c-9.79,0 -18.34,-7.21 -19.78,-17.18l-13.15 -92.17c-16.44,-9.12 -99.07,-50.65 -104.75,-62.17l-61.17 -124.22 -172.99 0c-9.47,19.25 -57.91,126.5 -69.41,132.89l-96.5 53.5 -13.15 92.17c-3.73,26.05 -43.31,20.44 -39.59,-5.64l14.56 -102.01c0.89,-6.21 4.63,-11.64 10.11,-14.68l99.71 -55.28 63.89 -129.77c3.36,-6.83 10.32,-11.18 17.94,-11.18l197.89 0c7.63,0 14.58,4.35 17.94,11.18l63.91 129.77 99.72 55.28c5.48,3.04 9.2,8.46 10.11,14.68l14.56 102.01c1.71,12.02 -7.75,22.81 -19.85,22.81z\" id=\"id_101\" style=\"fill: rgb(255, 255, 255);\"><\/path><path class=\"fil0\" d=\"M1239.23 1441.22c-8.69,0 -16.68,-5.7 -19.2,-14.48l-29.19 -101.53 -132.33 0 -29.19 101.53c-7.29,25.33 -45.7,14.23 -38.43,-11.04l33.33 -116.01c2.46,-8.57 10.3,-14.48 19.22,-14.48l162.48 0c8.93,0 16.76,5.91 19.22,14.48l33.33 116.01c3.7,12.87 -6.05,25.52 -19.22,25.52z\" id=\"id_102\" style=\"fill: rgb(255, 255, 255);\"><\/path><path class=\"fil0\" d=\"M669.14 1441.22c-8.69,0 -16.69,-5.7 -19.2,-14.48l-29.18 -101.53 -132.36 0 -29.18 101.53c-7.26,25.31 -45.7,14.25 -38.43,-11.04l33.33 -116.01c2.46,-8.57 10.3,-14.48 19.22,-14.48l162.47 0c8.92,0 16.76,5.91 19.22,14.48l33.33 116.01c3.7,12.89 -6.05,25.52 -19.23,25.52z\" id=\"id_103\" style=\"fill: rgb(255, 255, 255);\"><\/path><path class=\"fil1\" d=\"M1595.89 1441.22c-9.35,0 -17.69,-6.59 -19.58,-16.11l-76.56 -386.36 -117.09 6.79c-8.49,0.64 -16.94,-4.83 -19.97,-13.15l-135.57 -374.65 -116.55 -0.01c-6.39,0 -12.4,-3.06 -16.15,-8.21l-241.09 -330.61 -241.1 330.6c-3.76,5.16 -9.78,8.21 -16.17,8.21l-116.55 0 -135.54 374.65c-3.01,8.32 -11.07,13.73 -19.97,13.15l-82.24 -4.78c-26.35,-1.53 -23.88,-41.62 2.32,-39.92l67.35 3.9 135.26 -373.81c2.86,-7.92 10.39,-13.2 18.8,-13.2l120.43 0 251.25 -344.55c7.53,-10.32 24.8,-10.32 32.31,0l251.28 344.56 120.41 0c8.41,0 15.93,5.28 18.8,13.19l135.24 373.81 119.59 -6.93c9.78,-0.78 18.81,6.28 20.76,16.07l79.93 403.44c2.44,12.34 -7.09,23.89 -19.62,23.89z\" id=\"id_104\" style=\"fill: rgb(255, 255, 255);\"><\/path><path class=\"fil1\" d=\"M1686.54 1441.22l-1666.42 0c-26.32,0 -26.32,-39.99 0,-39.99l1666.42 0c26.32,0 26.32,39.99 0,39.99z\" id=\"id_105\" style=\"fill: rgb(255, 255, 255);\"><\/path><path class=\"fil1\" d=\"M432.63 1441.22c-65.56,0 -150.74,-367.32 -150.85,-367.49l-180.65 -131.2 -39.78 480.33c-2.19,26.28 -42.04,22.92 -39.86,-3.31l42.72 -515.75c1.29,-15.48 19.09,-23.63 31.68,-14.51l215.39 156.43c3.86,2.8 6.6,6.9 7.7,11.55 36.68,154.39 94.2,330.7 123.19,346.34 18.27,9.85 11.04,37.62 -9.53,37.62z\" id=\"id_106\" style=\"fill: rgb(255, 255, 255);\"><\/path><path class=\"fil1\" d=\"M342.05 1239.02c-17.63,0 -26.79,-21.51 -14.13,-34.15l168.09 -168.08 -135.04 -135.04c-18.64,-18.64 9.68,-46.9 28.27,-28.29l149.18 149.18c7.82,7.82 7.82,20.48 0,28.29l-182.23 182.24c-3.9,3.91 -9.03,5.86 -14.13,5.86z\" id=\"id_107\" style=\"fill: rgb(255, 255, 255);\"><\/path><path class=\"fil1\" d=\"M1440.02 1441.22c-9.35,0 -17.69,-6.59 -19.58,-16.11l-49.35 -249.09 -117.09 6.79c-8.37,0.65 -16.94,-4.84 -19.97,-13.15l-135.56 -374.65 -116.54 -0.01c-6.39,0 -12.41,-3.06 -16.15,-8.21l-242.96 -333.19c-15.45,-21.2 16.84,-44.74 32.31,-23.57l236.99 324.98 120.42 -0c8.41,0 15.93,5.27 18.8,13.19l135.24 373.81 119.59 -6.93c9.91,-0.69 18.81,6.28 20.76,16.06l52.72 266.16c2.45,12.33 -7.09,23.91 -19.62,23.91z\" id=\"id_108\" style=\"fill: rgb(255, 255, 255);\"><\/path><path class=\"fil1\" d=\"M227.77 1288.69c-11.98,0 -21.36,-10.6 -19.87,-22.48 7.12,-57.05 -107.98,-134.52 -148.88,-157.14 -23.06,-12.75 -3.67,-47.72 19.35,-35 18.56,10.26 180.94,103.07 169.2,197.09 -1.25,10.13 -9.87,17.53 -19.8,17.53z\" id=\"id_109\" style=\"fill: rgb(255, 255, 255);\"><\/path><path class=\"fil2\" d=\"M913.6 852.59l120.42 -0c8.41,0 15.93,5.27 18.8,13.19l135.24 373.81 119.59 -6.93c9.91,-0.69 18.81,6.28 20.76,16.06l30.21 152.5 57.07 0 -44.62 -225.2 -117.09 6.79c-8.37,0.65 -16.94,-4.84 -19.97,-13.15l-135.56 -374.65 -116.54 -0.01c-6.39,0 -12.41,-3.06 -16.15,-8.21l-226.81 -311.04 -50.08 68.67 224.73 308.17z\" id=\"id_110\" style=\"fill: rgb(255, 255, 255);\"><\/path><\/g><\/svg><\/div>                  \n                    <div class=\"ue_info\">\n            <div class=\"ue_main\">Das Leben <\/div>                                             <div class=\"ue_sub\"> <p>Das Leben ist in das Innere des Psiloritis vorgedrungen und hat Formen entwickelt, die sich so angepasst haben, dass sie an ewig dunklen Orten mit wenig Nahrung \u00fcberleben und sich fortpflanzen k\u00f6nnen. In v\u00f6lliger Dunkelheit und absoluter Finsternis kriechen oder kriechen die Troglodyten in den endlosen Tunneln, die durch die Risse im Untergrund entstanden sind, auf der Suche nach der knappen Nahrung und einem Partner.<\/p>\n <\/div>                                        <\/div>\n                      <\/div>\n      \n<\/div>\n<div id=\"uc_expanding_content_cards_elementor_eb09f31_item2\" class=\"ue_option elementor-repeater-item-eab6ab0 \" style=\"background-image:url(https:\/\/sfentoni-cave.com\/wp-content\/uploads\/2023\/06\/david-clode-8cw5JIEFnwE-unsplash-1.jpg);\">\n      <div class=\"ue_shadow\"><\/div>      <div class=\"ue_label\">\n         \n          <div class=\"ue_icon graphic_element_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"64\" height=\"64\" viewBox=\"0 0 64 64\" fill=\"none\"><path d=\"M60.23 61.33C59.9648 61.33 59.7105 61.2246 59.523 61.037L53.873 55.387C52.8534 54.3619 51.6406 53.5491 50.3048 52.9957C48.9691 52.4423 47.5368 52.1593 46.091 52.163H46.085C44.6413 52.1593 43.2114 52.4424 41.878 52.9958C40.5447 53.5493 39.3346 54.3621 38.318 55.387C38.1299 55.5742 37.8754 55.6796 37.61 55.68V55.68C37.4785 55.6801 37.3483 55.6543 37.2268 55.604C37.1053 55.5537 36.9949 55.48 36.902 55.387L36.232 54.717C33.8541 52.3295 30.8186 50.7049 27.5131 50.0505C24.2077 49.3961 20.7822 49.7416 17.674 51.043L11.825 53.483C11.642 53.5594 11.4405 53.5796 11.246 53.5412C11.0516 53.5028 10.8729 53.4074 10.7327 53.2673C10.5925 53.1271 10.4972 52.9484 10.4588 52.7539C10.4204 52.5595 10.4406 52.3579 10.517 52.175L12.957 46.325C14.2584 43.2168 14.6039 39.7913 13.9495 36.4858C13.2951 33.1804 11.6705 30.1449 9.28297 27.767L8.61297 27.098C8.51984 27.0051 8.44596 26.8948 8.39554 26.7733C8.34513 26.6518 8.31918 26.5215 8.31918 26.39C8.31918 26.2585 8.34513 26.1282 8.39554 26.0067C8.44596 25.8852 8.51984 25.7749 8.61297 25.682C9.63793 24.6654 10.4507 23.4553 11.0042 22.1219C11.5576 20.7886 11.8407 19.3586 11.837 17.915C11.8418 16.4681 11.5593 15.0346 11.0058 13.6978C10.4524 12.3609 9.63905 11.1472 8.61297 10.127L2.96297 4.47701C2.83282 4.34668 2.74118 4.18295 2.69818 4.00385C2.65517 3.82476 2.66246 3.63727 2.71924 3.46206C2.77603 3.28684 2.8801 3.13072 3.01998 3.0109C3.15986 2.89107 3.33012 2.81221 3.51197 2.78301L4.01197 2.70301C12.6128 1.35187 21.4185 2.90835 29.035 7.12601L30.32 7.84801C30.4548 7.92376 30.5701 8.02975 30.6571 8.15762C30.744 8.2855 30.8001 8.43179 30.8209 8.585C30.8417 8.73822 30.8268 8.89417 30.7771 9.04062C30.7275 9.18706 30.6446 9.32001 30.535 9.42901L29.115 10.839C27.1823 12.7834 26.0429 15.3776 25.9187 18.1163C25.7944 20.8549 26.6943 23.5417 28.443 25.653L33.363 20.733C33.4909 20.6052 33.6511 20.5145 33.8265 20.4705C34.0019 20.4266 34.186 20.431 34.359 20.4833C34.5321 20.5356 34.6878 20.6339 34.8095 20.7677C34.9311 20.9015 35.0143 21.0657 35.05 21.243L35.422 23.094C35.6917 24.4478 36.3566 25.6912 37.3326 26.6673C38.3087 27.6434 39.5522 28.3083 40.906 28.578L42.757 28.95C42.9342 28.9857 43.0985 29.0688 43.2323 29.1905C43.3661 29.3122 43.4643 29.4678 43.5167 29.6409C43.569 29.814 43.5734 29.9981 43.5294 30.1735C43.4855 30.3489 43.3948 30.5091 43.267 30.637L38.347 35.557C40.4589 37.3061 43.1465 38.206 45.8858 38.0812C48.6252 37.9564 51.2198 36.8159 53.164 34.882L54.571 33.465C54.68 33.3553 54.8129 33.2724 54.9594 33.2228C55.1058 33.1732 55.2618 33.1582 55.415 33.1791C55.5682 33.1999 55.7145 33.256 55.8424 33.3429C55.9702 33.4298 56.0762 33.5452 56.152 33.68L56.872 34.96C61.0899 42.5778 62.648 51.3844 61.3 59.987V59.987L61.22 60.487C61.1824 60.7218 61.0624 60.9355 60.8815 61.0898C60.7007 61.2441 60.4707 61.3289 60.233 61.329L60.23 61.33ZM46.091 50.163C47.8002 50.158 49.4935 50.4922 51.0727 51.1462C52.652 51.8002 54.0857 52.761 55.291 53.973L59.528 58.21C60.4212 50.5081 58.8827 42.7197 55.128 35.936L55.059 35.813L54.582 36.294C52.1395 38.7244 48.8341 40.0887 45.3885 40.0887C41.9429 40.0887 38.6374 38.7244 36.195 36.294C36.102 36.2011 36.0282 36.0908 35.9779 35.9694C35.9276 35.8481 35.9017 35.7179 35.9017 35.5865C35.9017 35.4551 35.9276 35.325 35.9779 35.2036C36.0282 35.0822 36.102 34.9719 36.195 34.879L40.535 30.539H40.515C38.7742 30.192 37.1753 29.3369 35.9202 28.0818C34.665 26.8267 33.81 25.2278 33.463 23.487V23.467L29.123 27.807C28.9355 27.9946 28.6812 28.0999 28.416 28.1C28.2845 28.1001 28.1543 28.0743 28.0328 28.024C27.9113 27.9737 27.8009 27.9 27.708 27.807C25.2788 25.3645 23.9152 22.0598 23.9152 18.615C23.9152 15.1702 25.2788 11.8655 27.708 9.42301L28.193 8.94301L28.066 8.87201C21.2829 5.11948 13.4965 3.58108 5.79597 4.47201L10.033 8.70901C11.2451 9.91416 12.206 11.3479 12.8601 12.9271C13.5141 14.5064 13.8482 16.1997 13.843 17.909C13.8502 21.0097 12.7393 24.0091 10.714 26.357C13.3793 29.0142 15.1927 32.4051 15.9229 36.0972C16.6532 39.7893 16.2671 43.6152 14.814 47.087L13.3 50.7L16.906 49.2C20.3774 47.7462 24.2032 47.3593 27.8955 48.0886C31.5877 48.8179 34.979 50.6304 37.637 53.295C39.9849 51.2697 42.9843 50.1588 46.085 50.166L46.091 50.163Z\" fill=\"#ffffff\" id=\"id_101\"><\/path><\/svg><\/div>                  \n                    <div class=\"ue_info\">\n            <div class=\"ue_main\">Die Flederm\u00e4use<\/div>                                             <div class=\"ue_sub\"> <p>Flederm\u00e4use produzieren riesige Kotmengen, weil sie jede Nacht so viele Insekten fressen, wie sie wiegen. Alle drei h\u00f6hlenbr\u00fctenden Arten geh\u00f6ren zur Familie der Rhinolophiden, deren Hauptmerkmal die morphologisch auff\u00e4llige Nase ist. Wenn sie tags\u00fcber an der H\u00f6hlendecke h\u00e4ngend schlafen, wickeln sie sich in ihre h\u00e4utigen Fl\u00fcgel ein, um den W\u00e4rmeverlust ihres K\u00f6rpers zu verringern.<\/p>\n <\/div>                                        <\/div>\n                      <\/div>\n      \n<\/div>\n<div id=\"uc_expanding_content_cards_elementor_eb09f31_item3\" class=\"ue_option elementor-repeater-item-10fe77e \" style=\"background-image:url(https:\/\/sfentoni-cave.com\/wp-content\/uploads\/2023\/06\/matt-seymour-KUdJISWV6kI-unsplash-1.jpg);\">\n      <div class=\"ue_shadow\"><\/div>      <div class=\"ue_label\">\n         \n          <div class=\"ue_icon graphic_element_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 64 64\"><g id=\"Layer_20\" data-name=\"Layer 20\"><path d=\"M10.83,35.58a1.89,1.89,0,0,0,0,3.78A1.89,1.89,0,0,0,10.83,35.58Z\" id=\"id_101\" style=\"fill: rgb(255, 255, 255);\"><\/path><path d=\"M59.85,28.72C54.29,17.48,54,17.42,36,14.35a1,1,0,0,0-.33,2c17.27,3,17.27,3,22.38,13.28,1.12,2.28,2,5.54-2.22,8.48-1.67-13.58-23.31-20.27-37.78-15-4.83-7.38-13.4-1.92-10.55,6.37A14.81,14.81,0,0,0,3,39.81c-.07,5.48,11.8,7.35,17.7,7.85H4a1,1,0,0,0,0,2H35.84a1,1,0,0,0,.52-1.83c9.7-.67,18.81-2.86,19.55-7.42C60.91,37.49,62.24,33.56,59.85,28.72ZM29.48,46.06C15.75,46.06,5,43.31,5,39.81a12.61,12.61,0,0,1,3.41-8.37c.7,1,1.41,2.25,2.6,2.5a1,1,0,0,0,.61-1.79c-3.22-2.26-3.77-9.28,0-10.38,4.18-.83,6.67,4.68,5.79,8.18a1,1,0,0,0,.73,1.21c2.27.35,1.39-4.93.81-6.23C32.74,20,54,26.69,54,39.81,54,43.31,43.21,46.06,29.48,46.06Z\" id=\"id_102\" style=\"fill: rgb(255, 255, 255);\"><\/path><path d=\"M41.69,47.66H39.16a1,1,0,0,0,0,2h2.53A1,1,0,0,0,41.69,47.66Z\" id=\"id_103\" style=\"fill: rgb(255, 255, 255);\"><\/path><path d=\"M55,47.66H45.2a1,1,0,0,0,0,2H55A1,1,0,0,0,55,47.66Z\" id=\"id_104\" style=\"fill: rgb(255, 255, 255);\"><\/path><\/g><\/svg><\/div>                  \n                    <div class=\"ue_info\">\n            <div class=\"ue_main\">Die Nagetiere<\/div>                                             <div class=\"ue_sub\"> <p>In der H\u00f6hle gibt es auch viele M\u00e4use, vor allem Ratten. Die \u00dcberreste ihrer Nahrung, wie z. B. Eichelschalen, sind, wenn sie verschimmelt sind, erstklassige Nahrung f\u00fcr h\u00f6hlenbewohnende Tiere, die Saprophyten.<\/p>\n <\/div>                                        <\/div>\n                      <\/div>\n      \n<\/div>\n<div id=\"uc_expanding_content_cards_elementor_eb09f31_item4\" class=\"ue_option elementor-repeater-item-dba24c4 \" style=\"background-image:url(https:\/\/sfentoni-cave.com\/wp-content\/uploads\/2023\/05\/grecaniscous-guanophilus-1-768x562.jpg);\">\n      <div class=\"ue_shadow\"><\/div>      <div class=\"ue_label\">\n         \n          <div class=\"ue_icon graphic_element_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 64 64\"><defs><style>.cls-1{fill:none;}.cls-1,.cls-2{stroke:#000;stroke-linecap:round;stroke-linejoin:round;stroke-width:2px;}.cls-2{fill:#bf7e68;}<\/style><\/defs><g id=\"scorpion\"><circle cx=\"9.93\" cy=\"49.4\" r=\"1.07\" id=\"id_101\" style=\"fill: rgb(255, 255, 255);\"><\/circle><circle cx=\"54.93\" cy=\"22.4\" r=\"1.07\" id=\"id_102\" style=\"fill: rgb(255, 255, 255);\"><\/circle><line class=\"cls-1\" x1=\"13\" y1=\"35\" x2=\"13\" y2=\"39\" id=\"id_103\" style=\"stroke: rgb(255, 255, 255);\"><\/line><line class=\"cls-1\" x1=\"11\" y1=\"37\" x2=\"15\" y2=\"37\" id=\"id_104\" style=\"stroke: rgb(255, 255, 255);\"><\/line><circle class=\"cls-1\" cx=\"19\" cy=\"53\" r=\"2\" id=\"id_105\" style=\"stroke: rgb(255, 255, 255);\"><\/circle><path class=\"cls-1\" d=\"M38.26,24.15a8.55,8.55,0,0,0,4.25-5\" id=\"id_106\" style=\"stroke: rgb(255, 255, 255);\"><\/path><path class=\"cls-1\" d=\"M46.4,20.11a12.7,12.7,0,0,1-6.69,7.8\" id=\"id_107\" style=\"stroke: rgb(255, 255, 255);\"><\/path><path class=\"cls-2\" d=\"M24.67,24.11a8.59,8.59,0,0,1-4.24-5.17\" id=\"id_108\" style=\"fill: rgb(255, 255, 255); stroke: rgb(255, 255, 255);\"><\/path><path class=\"cls-2\" d=\"M16.57,20a12.68,12.68,0,0,0,6.72,7.91\" id=\"id_109\" style=\"fill: rgb(255, 255, 255); stroke: rgb(255, 255, 255);\"><\/path><path class=\"cls-1\" d=\"M11.62.88c0,3.06,1.06,7.34,5.88,11.62a13.5,13.5,0,0,0,7.14-6.75A14.32,14.32,0,0,1,25,9c0,6.08-3.58,11-8,11S9,15.08,9,9A13.06,13.06,0,0,1,11.62.88Z\" id=\"id_110\" style=\"stroke: rgb(255, 255, 255);\"><\/path><line class=\"cls-1\" x1=\"22\" y1=\"22\" x2=\"20\" y2=\"25\" id=\"id_111\" style=\"stroke: rgb(255, 255, 255);\"><\/line><path class=\"cls-1\" d=\"M34,46.58V49a7,7,0,0,0,7,7c3.86,0,8-3.14,8-7V44\" id=\"id_112\" style=\"stroke: rgb(255, 255, 255);\"><\/path><path class=\"cls-1\" d=\"M53,44.43V49c0,7.17-4.83,13-12,13A13,13,0,0,1,28,49V45.93\" id=\"id_113\" style=\"stroke: rgb(255, 255, 255);\"><\/path><path class=\"cls-1\" d=\"M25.56,23A19.23,19.23,0,0,0,23,33c0,7.73,3.81,14,8.5,14S40,40.73,40,33a19.23,19.23,0,0,0-2.56-10Z\" id=\"id_114\" style=\"stroke: rgb(255, 255, 255);\"><\/path><line class=\"cls-1\" x1=\"41\" y1=\"22\" x2=\"43\" y2=\"25\" id=\"id_115\" style=\"stroke: rgb(255, 255, 255);\"><\/line><path class=\"cls-1\" d=\"M29,16s-4,1-.61,6.87\" id=\"id_116\" style=\"stroke: rgb(255, 255, 255);\"><\/path><path class=\"cls-1\" d=\"M34,16s4,1,.62,6.87\" id=\"id_117\" style=\"stroke: rgb(255, 255, 255);\"><\/path><circle cx=\"34.93\" cy=\"26.4\" r=\"1.07\" id=\"id_118\" style=\"fill: rgb(255, 255, 255);\"><\/circle><circle cx=\"27.93\" cy=\"26.4\" r=\"1.07\" id=\"id_119\" style=\"fill: rgb(255, 255, 255);\"><\/circle><line class=\"cls-1\" x1=\"34.08\" y1=\"50.8\" x2=\"28.73\" y2=\"52.81\" id=\"id_120\" style=\"stroke: rgb(255, 255, 255);\"><\/line><line class=\"cls-1\" x1=\"35.49\" y1=\"53.92\" x2=\"31.46\" y2=\"57.45\" id=\"id_121\" style=\"stroke: rgb(255, 255, 255);\"><\/line><line class=\"cls-1\" x1=\"38.36\" y1=\"55.89\" x2=\"36.29\" y2=\"60.88\" id=\"id_122\" style=\"stroke: rgb(255, 255, 255);\"><\/line><line class=\"cls-1\" x1=\"41.83\" y1=\"56.19\" x2=\"42.49\" y2=\"61.58\" id=\"id_123\" style=\"stroke: rgb(255, 255, 255);\"><\/line><line class=\"cls-1\" x1=\"45.41\" y1=\"54.98\" x2=\"48.08\" y2=\"59.36\" id=\"id_124\" style=\"stroke: rgb(255, 255, 255);\"><\/line><line class=\"cls-1\" x1=\"48.18\" y1=\"52.41\" x2=\"51.51\" y2=\"54.68\" id=\"id_125\" style=\"stroke: rgb(255, 255, 255);\"><\/line><line class=\"cls-1\" x1=\"49.39\" y1=\"48.68\" x2=\"52.47\" y2=\"49.04\" id=\"id_126\" style=\"stroke: rgb(255, 255, 255);\"><\/line><path class=\"cls-1\" d=\"M46.19,33.68s2.79-2.66,4,.67-2.39,6.12-1.86,8.38,4.52,2.8,5.72.27,1.73-10.78-2.26-12.38S46.19,33.68,46.19,33.68Z\" id=\"id_127\" style=\"stroke: rgb(255, 255, 255);\"><\/path><line class=\"cls-1\" x1=\"17.52\" y1=\"12.5\" x2=\"19.6\" y2=\"14.27\" id=\"id_128\" style=\"stroke: rgb(255, 255, 255);\"><\/line><path class=\"cls-1\" d=\"M51.38.88c0,3.06-1.06,7.34-5.88,11.62a13.5,13.5,0,0,1-7.14-6.75A14.32,14.32,0,0,0,38,9c0,6.08,3.58,11,8,11s8-4.92,8-11A13.06,13.06,0,0,0,51.38.88Z\" id=\"id_129\" style=\"stroke: rgb(255, 255, 255);\"><\/path><line class=\"cls-1\" x1=\"45.48\" y1=\"12.5\" x2=\"43.4\" y2=\"14.27\" id=\"id_130\" style=\"stroke: rgb(255, 255, 255);\"><\/line><\/g><\/svg><\/div>                  \n                    <div class=\"ue_info\">\n            <div class=\"ue_main\">Die wirbellosen Tiere<\/div>                                             <div class=\"ue_sub\"> <p>In der H\u00f6hle leben mehrere Arten wirbelloser Tiere. Die wichtigsten von ihnen sind Isopoden, Pseudoskorpione, Zweibeiner, Diptera und Schnecken. Sie alle sind winzig klein, schlank, farblos und blind. Keiner von ihnen kann in der freien Natur leben, da sie den Klimaver\u00e4nderungen nicht standhalten k\u00f6nnen. Sie nehmen ihre Umwelt mit ihren hochsensiblen taktilen und chemischen Sinnen wahr und k\u00f6nnen lange Zeitr\u00e4ume des Hungers \u00fcberstehen. Diese Arten haben eine sehr begrenzte geografische Verbreitung, sehr kleine Populationen und bilden die troglobische H\u00f6hlenwelt.<\/p>\n <\/div>                                        <\/div>\n                      <\/div>\n      \n<\/div>\n\n  <\/div>\n<\/div>\n<!-- end Expanding Content Cards -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b537461 elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-mobile elementor-widget elementor-widget-ucaddon_expanding_content_cards\" data-id=\"b537461\" data-element_type=\"widget\" data-widget_type=\"ucaddon_expanding_content_cards.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Expanding Content Cards -->\n\n<style>\/* widget: Expanding Content Cards *\/\n\n\r\n@keyframes uc_expanding_content_cards_elementor_b537461__item-animation {\r\n  0% {\r\n            transform: translateX(50px);\r\n        \t        \tfilter: blur(10px);\r\n\t\t\t\r\n    \t    opacity: 0;\r\n  }\r\n  100% {\r\n            transform: translateX(0px);\r\n        \t            filter: blur(0px);\r\n            \r\n    \t\topacity: 1;\r\n  }\r\n}\r\n\r\n\r\n#uc_expanding_content_cards_elementor_b537461 .ue_option{\r\n\topacity:0;\r\n}\r\n\r\n\r\n#uc_expanding_content_cards_elementor_b537461 .uc-entrance-animate {\r\n  opacity:1;\r\n}\r\n\r\n#uc_expanding_content_cards_elementor_b537461 .uc-entrance-animate {\r\n\tanimation: uc_expanding_content_cards_elementor_b537461__item-animation 0.6s cubic-bezier(0.470, 0.000, 0.745, 0.715) both;\r\n}\r\n\r\n\t\t\t\n\n#uc_expanding_content_cards_elementor_b537461.exp-wrapper {\n  box-sizing: border-box;\n  display: flex;\n  flex-direction: row;\n  justify-content: center;\n  align-items: center;\n}\n#uc_expanding_content_cards_elementor_b537461.exp-wrapper{\n  width:100%;\n}\n#uc_expanding_content_cards_elementor_b537461.exp-wrapper .ue_options {\n  display: flex;\n  align-items: center;\n  flex-direction: row;\n  justify-content: center;\n  min-width: 200px;\n  width:100%;\n}\n#uc_expanding_content_cards_elementor_b537461.exp-wrapper .ue_options .ue_option {\n  box-sizing: border-box;\n  display: flex;\n  position: relative;\n  overflow: hidden;\n  cursor: pointer;\n  justify-content: center;\n  background-position: center;\n  background-repeat: no-repeat;\n  background-size: cover;\n\n}\n#uc_expanding_content_cards_elementor_b537461.exp-wrapper .ue_options .ue_option.active {\n  flex-grow: 10000;\n}\n\n#uc_expanding_content_cards_elementor_b537461.exp-wrapper .ue_options .ue_option:not(.active) {\n  justify-content: center;\n}\n#uc_expanding_content_cards_elementor_b537461.exp-wrapper .ue_options .ue_option .ue_shadow {\n  position: absolute;\n  bottom: 0px;\n  left: 0px;\n  right: 0px;\n  height: 100%;\n  z-index:1;\n  transition: 800ms;\n}\n#uc_expanding_content_cards_elementor_b537461.exp-wrapper .ue_option:not(.active) .ue_label {\n  align-items: center;\n}\n#uc_expanding_content_cards_elementor_b537461.exp-wrapper .ue_options .ue_option .ue_label {\n  display: flex;\n  z-index:2;\n  transition: 0.5s cubic-bezier(0.05, 0.61, 0.41, 0.95);\n}\n#uc_expanding_content_cards_elementor_b537461.exp-wrapper .ue_options .ue_option.active .ue_label{\n  animation-name: sub-content-fade;\n  animation-duration: 800ms;\n}\n@keyframes sub-content-fade{\n  0%   {opacity:0;}\n  80%  {opacity:0;}\n  100% {opacity:1;}\n}\n\n\n#uc_expanding_content_cards_elementor_b537461.exp-wrapper .ue_options .ue_option.active .ue_label .ue_info > div {\n  left: 0px;\n  width:100%;\n}\n#uc_expanding_content_cards_elementor_b537461.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_info > div {\n  left: 0px;\n  opacity: 0;\n  width: 0px;\n  height: 0px;\n  transition: width 0ms;\n}\n\n#uc_expanding_content_cards_elementor_b537461.exp-wrapper .ue_options .ue_option .ue_label .ue_info > div {\n  position: relative;\n  transition: 0.5s cubic-bezier(0.05, 0.61, 0.41, 0.95), opacity 0.5s ease-out;\n}\n#uc_expanding_content_cards_elementor_b537461.exp-wrapper  .ue_options .ue_option .ue_label .ue_info {\n  display: flex;\n  align-items: center;\n  justify-content: center;\n}\n\n#uc_expanding_content_cards_elementor_b537461.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_info {\n  margin-left: 0px!important;\n}\n#uc_expanding_content_cards_elementor_b537461.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_info .ue_main {\n  opacity: 1;\n  width: auto;\n  height: auto;\n  writing-mode: vertical-rl;\n  text-orientation: mixed;\n  text-decoration: none;\n}\n\n#uc_expanding_content_cards_elementor_b537461.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_sub {\n  height:0;\n  margin-top: 0px;\n}\n\n#uc_expanding_content_cards_elementor_b537461.exp-wrapper .ue_options .ue_option .ue_label .ue_icon {\n  display: flex;\n  flex-shrink: 0;\n  flex-direction: row;\n  justify-content: center;\n  align-items: center;\n  overflow: hidden;\n  transition: 0.5s;\n}\n\n@media screen and (max-width: 520px) {\n#uc_expanding_content_cards_elementor_b537461.exp-wrapper .ue_options {\n  display: grid;\n}\n#uc_expanding_content_cards_elementor_b537461.exp-wrapper .ue_options .ue_option{\n    width: 100%;\n}\n#uc_expanding_content_cards_elementor_b537461.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_info {\n  margin-left: 0px!important;\n}\n\n#uc_expanding_content_cards_elementor_b537461.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_info .ue_main {\n  opacity: 1;\n  width: auto;\n  height: auto;\n  writing-mode: horizontal-tb;\n  text-orientation: mixed;\n  text-decoration: none;\n  transform: rotate(0deg);\n}\n  \n  \n\n#uc_expanding_content_cards_elementor_b537461.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_info > div {\n  opacity:1;\n  width:100%;\n  height:auto;\n}\n#uc_expanding_content_cards_elementor_b537461.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_sub {\n  height:auto;\n}\n \n}\n\n<\/style>\n\n<div id=\"uc_expanding_content_cards_elementor_b537461\" class=\"exp-wrapper  \" data-selectedItem=\"\"  >\n  <div class=\"ue_options uc-items-wrapper\">\n   <div id=\"uc_expanding_content_cards_elementor_b537461_item1\" class=\"ue_option elementor-repeater-item-0984f7c  active \" style=\"background-image:url(https:\/\/sfentoni-cave.com\/wp-content\/uploads\/2022\/09\/coming-soon-768x432.jpg);\">\n      <div class=\"ue_shadow\"><\/div>      <div class=\"ue_label\">\n         \n          <div class=\"ue_icon graphic_element_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:xodm=\"http:\/\/www.corel.com\/coreldraw\/odm\/2003\" xml:space=\"preserve\" width=\"1.70666in\" height=\"1.70666in\" style=\"shape-rendering:geometricPrecision; text-rendering:geometricPrecision; image-rendering:optimizeQuality; fill-rule:evenodd; clip-rule:evenodd\" viewBox=\"0 0 1706.66 1706.66\"><defs><style type=\"text\/css\">       .fil1 {fill:#000066}    .fil2 {fill:#DADADA}    .fil0 {fill:#FF6600}     <\/style><\/defs><g id=\"Layer_x0020_1\"><metadata id=\"CorelCorpID_0Corel-Layer\"><\/metadata><path class=\"fil0\" d=\"M1124.97 1325.21c-9.79,0 -18.34,-7.21 -19.78,-17.18l-13.15 -92.17c-16.44,-9.12 -99.07,-50.65 -104.75,-62.17l-61.17 -124.22 -172.99 0c-9.47,19.25 -57.91,126.5 -69.41,132.89l-96.5 53.5 -13.15 92.17c-3.73,26.05 -43.31,20.44 -39.59,-5.64l14.56 -102.01c0.89,-6.21 4.63,-11.64 10.11,-14.68l99.71 -55.28 63.89 -129.77c3.36,-6.83 10.32,-11.18 17.94,-11.18l197.89 0c7.63,0 14.58,4.35 17.94,11.18l63.91 129.77 99.72 55.28c5.48,3.04 9.2,8.46 10.11,14.68l14.56 102.01c1.71,12.02 -7.75,22.81 -19.85,22.81z\" id=\"id_101\" style=\"fill: rgb(255, 255, 255);\"><\/path><path class=\"fil0\" d=\"M1239.23 1441.22c-8.69,0 -16.68,-5.7 -19.2,-14.48l-29.19 -101.53 -132.33 0 -29.19 101.53c-7.29,25.33 -45.7,14.23 -38.43,-11.04l33.33 -116.01c2.46,-8.57 10.3,-14.48 19.22,-14.48l162.48 0c8.93,0 16.76,5.91 19.22,14.48l33.33 116.01c3.7,12.87 -6.05,25.52 -19.22,25.52z\" id=\"id_102\" style=\"fill: rgb(255, 255, 255);\"><\/path><path class=\"fil0\" d=\"M669.14 1441.22c-8.69,0 -16.69,-5.7 -19.2,-14.48l-29.18 -101.53 -132.36 0 -29.18 101.53c-7.26,25.31 -45.7,14.25 -38.43,-11.04l33.33 -116.01c2.46,-8.57 10.3,-14.48 19.22,-14.48l162.47 0c8.92,0 16.76,5.91 19.22,14.48l33.33 116.01c3.7,12.89 -6.05,25.52 -19.23,25.52z\" id=\"id_103\" style=\"fill: rgb(255, 255, 255);\"><\/path><path class=\"fil1\" d=\"M1595.89 1441.22c-9.35,0 -17.69,-6.59 -19.58,-16.11l-76.56 -386.36 -117.09 6.79c-8.49,0.64 -16.94,-4.83 -19.97,-13.15l-135.57 -374.65 -116.55 -0.01c-6.39,0 -12.4,-3.06 -16.15,-8.21l-241.09 -330.61 -241.1 330.6c-3.76,5.16 -9.78,8.21 -16.17,8.21l-116.55 0 -135.54 374.65c-3.01,8.32 -11.07,13.73 -19.97,13.15l-82.24 -4.78c-26.35,-1.53 -23.88,-41.62 2.32,-39.92l67.35 3.9 135.26 -373.81c2.86,-7.92 10.39,-13.2 18.8,-13.2l120.43 0 251.25 -344.55c7.53,-10.32 24.8,-10.32 32.31,0l251.28 344.56 120.41 0c8.41,0 15.93,5.28 18.8,13.19l135.24 373.81 119.59 -6.93c9.78,-0.78 18.81,6.28 20.76,16.07l79.93 403.44c2.44,12.34 -7.09,23.89 -19.62,23.89z\" id=\"id_104\" style=\"fill: rgb(255, 255, 255);\"><\/path><path class=\"fil1\" d=\"M1686.54 1441.22l-1666.42 0c-26.32,0 -26.32,-39.99 0,-39.99l1666.42 0c26.32,0 26.32,39.99 0,39.99z\" id=\"id_105\" style=\"fill: rgb(255, 255, 255);\"><\/path><path class=\"fil1\" d=\"M432.63 1441.22c-65.56,0 -150.74,-367.32 -150.85,-367.49l-180.65 -131.2 -39.78 480.33c-2.19,26.28 -42.04,22.92 -39.86,-3.31l42.72 -515.75c1.29,-15.48 19.09,-23.63 31.68,-14.51l215.39 156.43c3.86,2.8 6.6,6.9 7.7,11.55 36.68,154.39 94.2,330.7 123.19,346.34 18.27,9.85 11.04,37.62 -9.53,37.62z\" id=\"id_106\" style=\"fill: rgb(255, 255, 255);\"><\/path><path class=\"fil1\" d=\"M342.05 1239.02c-17.63,0 -26.79,-21.51 -14.13,-34.15l168.09 -168.08 -135.04 -135.04c-18.64,-18.64 9.68,-46.9 28.27,-28.29l149.18 149.18c7.82,7.82 7.82,20.48 0,28.29l-182.23 182.24c-3.9,3.91 -9.03,5.86 -14.13,5.86z\" id=\"id_107\" style=\"fill: rgb(255, 255, 255);\"><\/path><path class=\"fil1\" d=\"M1440.02 1441.22c-9.35,0 -17.69,-6.59 -19.58,-16.11l-49.35 -249.09 -117.09 6.79c-8.37,0.65 -16.94,-4.84 -19.97,-13.15l-135.56 -374.65 -116.54 -0.01c-6.39,0 -12.41,-3.06 -16.15,-8.21l-242.96 -333.19c-15.45,-21.2 16.84,-44.74 32.31,-23.57l236.99 324.98 120.42 -0c8.41,0 15.93,5.27 18.8,13.19l135.24 373.81 119.59 -6.93c9.91,-0.69 18.81,6.28 20.76,16.06l52.72 266.16c2.45,12.33 -7.09,23.91 -19.62,23.91z\" id=\"id_108\" style=\"fill: rgb(255, 255, 255);\"><\/path><path class=\"fil1\" d=\"M227.77 1288.69c-11.98,0 -21.36,-10.6 -19.87,-22.48 7.12,-57.05 -107.98,-134.52 -148.88,-157.14 -23.06,-12.75 -3.67,-47.72 19.35,-35 18.56,10.26 180.94,103.07 169.2,197.09 -1.25,10.13 -9.87,17.53 -19.8,17.53z\" id=\"id_109\" style=\"fill: rgb(255, 255, 255);\"><\/path><path class=\"fil2\" d=\"M913.6 852.59l120.42 -0c8.41,0 15.93,5.27 18.8,13.19l135.24 373.81 119.59 -6.93c9.91,-0.69 18.81,6.28 20.76,16.06l30.21 152.5 57.07 0 -44.62 -225.2 -117.09 6.79c-8.37,0.65 -16.94,-4.84 -19.97,-13.15l-135.56 -374.65 -116.54 -0.01c-6.39,0 -12.41,-3.06 -16.15,-8.21l-226.81 -311.04 -50.08 68.67 224.73 308.17z\" id=\"id_110\" style=\"fill: rgb(255, 255, 255);\"><\/path><\/g><\/svg><\/div>                  \n                    <div class=\"ue_info\">\n            <div class=\"ue_main\">Das Leben <\/div>                                             <div class=\"ue_sub\"> <p>Das Leben ist in das Innere des Psiloritis vorgedrungen und hat Formen entwickelt, die sich so angepasst haben, dass sie an ewig dunklen Orten mit wenig Nahrung \u00fcberleben und sich fortpflanzen k\u00f6nnen. In v\u00f6lliger Dunkelheit und absoluter Finsternis kriechen oder kriechen die Troglodyten in den endlosen Tunneln, die durch die Risse im Untergrund entstanden sind, auf der Suche nach der knappen Nahrung und einem Partner.<\/p>\n <\/div>                                        <\/div>\n                      <\/div>\n      \n<\/div>\n<div id=\"uc_expanding_content_cards_elementor_b537461_item2\" class=\"ue_option elementor-repeater-item-eab6ab0 \" style=\"background-image:url(https:\/\/sfentoni-cave.com\/wp-content\/uploads\/2023\/06\/david-clode-8cw5JIEFnwE-unsplash-1.jpg);\">\n      <div class=\"ue_shadow\"><\/div>      <div class=\"ue_label\">\n         \n          <div class=\"ue_icon graphic_element_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"64\" height=\"64\" viewBox=\"0 0 64 64\" fill=\"none\"><path d=\"M60.23 61.33C59.9648 61.33 59.7105 61.2246 59.523 61.037L53.873 55.387C52.8534 54.3619 51.6406 53.5491 50.3048 52.9957C48.9691 52.4423 47.5368 52.1593 46.091 52.163H46.085C44.6413 52.1593 43.2114 52.4424 41.878 52.9958C40.5447 53.5493 39.3346 54.3621 38.318 55.387C38.1299 55.5742 37.8754 55.6796 37.61 55.68V55.68C37.4785 55.6801 37.3483 55.6543 37.2268 55.604C37.1053 55.5537 36.9949 55.48 36.902 55.387L36.232 54.717C33.8541 52.3295 30.8186 50.7049 27.5131 50.0505C24.2077 49.3961 20.7822 49.7416 17.674 51.043L11.825 53.483C11.642 53.5594 11.4405 53.5796 11.246 53.5412C11.0516 53.5028 10.8729 53.4074 10.7327 53.2673C10.5925 53.1271 10.4972 52.9484 10.4588 52.7539C10.4204 52.5595 10.4406 52.3579 10.517 52.175L12.957 46.325C14.2584 43.2168 14.6039 39.7913 13.9495 36.4858C13.2951 33.1804 11.6705 30.1449 9.28297 27.767L8.61297 27.098C8.51984 27.0051 8.44596 26.8948 8.39554 26.7733C8.34513 26.6518 8.31918 26.5215 8.31918 26.39C8.31918 26.2585 8.34513 26.1282 8.39554 26.0067C8.44596 25.8852 8.51984 25.7749 8.61297 25.682C9.63793 24.6654 10.4507 23.4553 11.0042 22.1219C11.5576 20.7886 11.8407 19.3586 11.837 17.915C11.8418 16.4681 11.5593 15.0346 11.0058 13.6978C10.4524 12.3609 9.63905 11.1472 8.61297 10.127L2.96297 4.47701C2.83282 4.34668 2.74118 4.18295 2.69818 4.00385C2.65517 3.82476 2.66246 3.63727 2.71924 3.46206C2.77603 3.28684 2.8801 3.13072 3.01998 3.0109C3.15986 2.89107 3.33012 2.81221 3.51197 2.78301L4.01197 2.70301C12.6128 1.35187 21.4185 2.90835 29.035 7.12601L30.32 7.84801C30.4548 7.92376 30.5701 8.02975 30.6571 8.15762C30.744 8.2855 30.8001 8.43179 30.8209 8.585C30.8417 8.73822 30.8268 8.89417 30.7771 9.04062C30.7275 9.18706 30.6446 9.32001 30.535 9.42901L29.115 10.839C27.1823 12.7834 26.0429 15.3776 25.9187 18.1163C25.7944 20.8549 26.6943 23.5417 28.443 25.653L33.363 20.733C33.4909 20.6052 33.6511 20.5145 33.8265 20.4705C34.0019 20.4266 34.186 20.431 34.359 20.4833C34.5321 20.5356 34.6878 20.6339 34.8095 20.7677C34.9311 20.9015 35.0143 21.0657 35.05 21.243L35.422 23.094C35.6917 24.4478 36.3566 25.6912 37.3326 26.6673C38.3087 27.6434 39.5522 28.3083 40.906 28.578L42.757 28.95C42.9342 28.9857 43.0985 29.0688 43.2323 29.1905C43.3661 29.3122 43.4643 29.4678 43.5167 29.6409C43.569 29.814 43.5734 29.9981 43.5294 30.1735C43.4855 30.3489 43.3948 30.5091 43.267 30.637L38.347 35.557C40.4589 37.3061 43.1465 38.206 45.8858 38.0812C48.6252 37.9564 51.2198 36.8159 53.164 34.882L54.571 33.465C54.68 33.3553 54.8129 33.2724 54.9594 33.2228C55.1058 33.1732 55.2618 33.1582 55.415 33.1791C55.5682 33.1999 55.7145 33.256 55.8424 33.3429C55.9702 33.4298 56.0762 33.5452 56.152 33.68L56.872 34.96C61.0899 42.5778 62.648 51.3844 61.3 59.987V59.987L61.22 60.487C61.1824 60.7218 61.0624 60.9355 60.8815 61.0898C60.7007 61.2441 60.4707 61.3289 60.233 61.329L60.23 61.33ZM46.091 50.163C47.8002 50.158 49.4935 50.4922 51.0727 51.1462C52.652 51.8002 54.0857 52.761 55.291 53.973L59.528 58.21C60.4212 50.5081 58.8827 42.7197 55.128 35.936L55.059 35.813L54.582 36.294C52.1395 38.7244 48.8341 40.0887 45.3885 40.0887C41.9429 40.0887 38.6374 38.7244 36.195 36.294C36.102 36.2011 36.0282 36.0908 35.9779 35.9694C35.9276 35.8481 35.9017 35.7179 35.9017 35.5865C35.9017 35.4551 35.9276 35.325 35.9779 35.2036C36.0282 35.0822 36.102 34.9719 36.195 34.879L40.535 30.539H40.515C38.7742 30.192 37.1753 29.3369 35.9202 28.0818C34.665 26.8267 33.81 25.2278 33.463 23.487V23.467L29.123 27.807C28.9355 27.9946 28.6812 28.0999 28.416 28.1C28.2845 28.1001 28.1543 28.0743 28.0328 28.024C27.9113 27.9737 27.8009 27.9 27.708 27.807C25.2788 25.3645 23.9152 22.0598 23.9152 18.615C23.9152 15.1702 25.2788 11.8655 27.708 9.42301L28.193 8.94301L28.066 8.87201C21.2829 5.11948 13.4965 3.58108 5.79597 4.47201L10.033 8.70901C11.2451 9.91416 12.206 11.3479 12.8601 12.9271C13.5141 14.5064 13.8482 16.1997 13.843 17.909C13.8502 21.0097 12.7393 24.0091 10.714 26.357C13.3793 29.0142 15.1927 32.4051 15.9229 36.0972C16.6532 39.7893 16.2671 43.6152 14.814 47.087L13.3 50.7L16.906 49.2C20.3774 47.7462 24.2032 47.3593 27.8955 48.0886C31.5877 48.8179 34.979 50.6304 37.637 53.295C39.9849 51.2697 42.9843 50.1588 46.085 50.166L46.091 50.163Z\" fill=\"#ffffff\" id=\"id_101\"><\/path><\/svg><\/div>                  \n                    <div class=\"ue_info\">\n            <div class=\"ue_main\">Die Flederm\u00e4use<\/div>                                             <div class=\"ue_sub\"> <p>Flederm\u00e4use produzieren riesige Kotmengen, weil sie jede Nacht so viele Insekten fressen, wie sie wiegen. Alle drei h\u00f6hlenbr\u00fctenden Arten geh\u00f6ren zur Familie der Rhinolophiden, deren Hauptmerkmal die morphologisch auff\u00e4llige Nase ist. Wenn sie tags\u00fcber an der H\u00f6hlendecke h\u00e4ngend schlafen, wickeln sie sich in ihre h\u00e4utigen Fl\u00fcgel ein, um den W\u00e4rmeverlust ihres K\u00f6rpers zu verringern.<\/p>\n <\/div>                                        <\/div>\n                      <\/div>\n      \n<\/div>\n\n  <\/div>\n<\/div>\n<!-- end Expanding Content Cards -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1dd6c2 elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-mobile elementor-widget elementor-widget-ucaddon_expanding_content_cards\" data-id=\"a1dd6c2\" data-element_type=\"widget\" data-widget_type=\"ucaddon_expanding_content_cards.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Expanding Content Cards -->\n\n<style>\/* widget: Expanding Content Cards *\/\n\n\r\n@keyframes uc_expanding_content_cards_elementor_a1dd6c2__item-animation {\r\n  0% {\r\n            transform: translateX(50px);\r\n        \t        \tfilter: blur(10px);\r\n\t\t\t\r\n    \t    opacity: 0;\r\n  }\r\n  100% {\r\n            transform: translateX(0px);\r\n        \t            filter: blur(0px);\r\n            \r\n    \t\topacity: 1;\r\n  }\r\n}\r\n\r\n\r\n#uc_expanding_content_cards_elementor_a1dd6c2 .ue_option{\r\n\topacity:0;\r\n}\r\n\r\n\r\n#uc_expanding_content_cards_elementor_a1dd6c2 .uc-entrance-animate {\r\n  opacity:1;\r\n}\r\n\r\n#uc_expanding_content_cards_elementor_a1dd6c2 .uc-entrance-animate {\r\n\tanimation: uc_expanding_content_cards_elementor_a1dd6c2__item-animation 0.6s cubic-bezier(0.470, 0.000, 0.745, 0.715) both;\r\n}\r\n\r\n\t\t\t\n\n#uc_expanding_content_cards_elementor_a1dd6c2.exp-wrapper {\n  box-sizing: border-box;\n  display: flex;\n  flex-direction: row;\n  justify-content: center;\n  align-items: center;\n}\n#uc_expanding_content_cards_elementor_a1dd6c2.exp-wrapper{\n  width:100%;\n}\n#uc_expanding_content_cards_elementor_a1dd6c2.exp-wrapper .ue_options {\n  display: flex;\n  align-items: center;\n  flex-direction: row;\n  justify-content: center;\n  min-width: 200px;\n  width:100%;\n}\n#uc_expanding_content_cards_elementor_a1dd6c2.exp-wrapper .ue_options .ue_option {\n  box-sizing: border-box;\n  display: flex;\n  position: relative;\n  overflow: hidden;\n  cursor: pointer;\n  justify-content: center;\n  background-position: center;\n  background-repeat: no-repeat;\n  background-size: cover;\n\n}\n#uc_expanding_content_cards_elementor_a1dd6c2.exp-wrapper .ue_options .ue_option.active {\n  flex-grow: 10000;\n}\n\n#uc_expanding_content_cards_elementor_a1dd6c2.exp-wrapper .ue_options .ue_option:not(.active) {\n  justify-content: center;\n}\n#uc_expanding_content_cards_elementor_a1dd6c2.exp-wrapper .ue_options .ue_option .ue_shadow {\n  position: absolute;\n  bottom: 0px;\n  left: 0px;\n  right: 0px;\n  height: 100%;\n  z-index:1;\n  transition: 800ms;\n}\n#uc_expanding_content_cards_elementor_a1dd6c2.exp-wrapper .ue_option:not(.active) .ue_label {\n  align-items: center;\n}\n#uc_expanding_content_cards_elementor_a1dd6c2.exp-wrapper .ue_options .ue_option .ue_label {\n  display: flex;\n  z-index:2;\n  transition: 0.5s cubic-bezier(0.05, 0.61, 0.41, 0.95);\n}\n#uc_expanding_content_cards_elementor_a1dd6c2.exp-wrapper .ue_options .ue_option.active .ue_label{\n  animation-name: sub-content-fade;\n  animation-duration: 800ms;\n}\n@keyframes sub-content-fade{\n  0%   {opacity:0;}\n  80%  {opacity:0;}\n  100% {opacity:1;}\n}\n\n\n#uc_expanding_content_cards_elementor_a1dd6c2.exp-wrapper .ue_options .ue_option.active .ue_label .ue_info > div {\n  left: 0px;\n  width:100%;\n}\n#uc_expanding_content_cards_elementor_a1dd6c2.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_info > div {\n  left: 0px;\n  opacity: 0;\n  width: 0px;\n  height: 0px;\n  transition: width 0ms;\n}\n\n#uc_expanding_content_cards_elementor_a1dd6c2.exp-wrapper .ue_options .ue_option .ue_label .ue_info > div {\n  position: relative;\n  transition: 0.5s cubic-bezier(0.05, 0.61, 0.41, 0.95), opacity 0.5s ease-out;\n}\n#uc_expanding_content_cards_elementor_a1dd6c2.exp-wrapper  .ue_options .ue_option .ue_label .ue_info {\n  display: flex;\n  align-items: center;\n  justify-content: center;\n}\n\n#uc_expanding_content_cards_elementor_a1dd6c2.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_info {\n  margin-left: 0px!important;\n}\n#uc_expanding_content_cards_elementor_a1dd6c2.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_info .ue_main {\n  opacity: 1;\n  width: auto;\n  height: auto;\n  writing-mode: vertical-rl;\n  text-orientation: mixed;\n  text-decoration: none;\n}\n\n#uc_expanding_content_cards_elementor_a1dd6c2.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_sub {\n  height:0;\n  margin-top: 0px;\n}\n\n#uc_expanding_content_cards_elementor_a1dd6c2.exp-wrapper .ue_options .ue_option .ue_label .ue_icon {\n  display: flex;\n  flex-shrink: 0;\n  flex-direction: row;\n  justify-content: center;\n  align-items: center;\n  overflow: hidden;\n  transition: 0.5s;\n}\n\n@media screen and (max-width: 520px) {\n#uc_expanding_content_cards_elementor_a1dd6c2.exp-wrapper .ue_options {\n  display: grid;\n}\n#uc_expanding_content_cards_elementor_a1dd6c2.exp-wrapper .ue_options .ue_option{\n    width: 100%;\n}\n#uc_expanding_content_cards_elementor_a1dd6c2.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_info {\n  margin-left: 0px!important;\n}\n\n#uc_expanding_content_cards_elementor_a1dd6c2.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_info .ue_main {\n  opacity: 1;\n  width: auto;\n  height: auto;\n  writing-mode: horizontal-tb;\n  text-orientation: mixed;\n  text-decoration: none;\n  transform: rotate(0deg);\n}\n  \n  \n\n#uc_expanding_content_cards_elementor_a1dd6c2.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_info > div {\n  opacity:1;\n  width:100%;\n  height:auto;\n}\n#uc_expanding_content_cards_elementor_a1dd6c2.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_sub {\n  height:auto;\n}\n \n}\n\n<\/style>\n\n<div id=\"uc_expanding_content_cards_elementor_a1dd6c2\" class=\"exp-wrapper  \" data-selectedItem=\"\"  >\n  <div class=\"ue_options uc-items-wrapper\">\n   <div id=\"uc_expanding_content_cards_elementor_a1dd6c2_item1\" class=\"ue_option elementor-repeater-item-10fe77e  active \" style=\"background-image:url(https:\/\/sfentoni-cave.com\/wp-content\/uploads\/2023\/06\/matt-seymour-KUdJISWV6kI-unsplash-1.jpg);\">\n      <div class=\"ue_shadow\"><\/div>      <div class=\"ue_label\">\n         \n          <div class=\"ue_icon graphic_element_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 64 64\"><g id=\"Layer_20\" data-name=\"Layer 20\"><path d=\"M10.83,35.58a1.89,1.89,0,0,0,0,3.78A1.89,1.89,0,0,0,10.83,35.58Z\" id=\"id_101\" style=\"fill: rgb(255, 255, 255);\"><\/path><path d=\"M59.85,28.72C54.29,17.48,54,17.42,36,14.35a1,1,0,0,0-.33,2c17.27,3,17.27,3,22.38,13.28,1.12,2.28,2,5.54-2.22,8.48-1.67-13.58-23.31-20.27-37.78-15-4.83-7.38-13.4-1.92-10.55,6.37A14.81,14.81,0,0,0,3,39.81c-.07,5.48,11.8,7.35,17.7,7.85H4a1,1,0,0,0,0,2H35.84a1,1,0,0,0,.52-1.83c9.7-.67,18.81-2.86,19.55-7.42C60.91,37.49,62.24,33.56,59.85,28.72ZM29.48,46.06C15.75,46.06,5,43.31,5,39.81a12.61,12.61,0,0,1,3.41-8.37c.7,1,1.41,2.25,2.6,2.5a1,1,0,0,0,.61-1.79c-3.22-2.26-3.77-9.28,0-10.38,4.18-.83,6.67,4.68,5.79,8.18a1,1,0,0,0,.73,1.21c2.27.35,1.39-4.93.81-6.23C32.74,20,54,26.69,54,39.81,54,43.31,43.21,46.06,29.48,46.06Z\" id=\"id_102\" style=\"fill: rgb(255, 255, 255);\"><\/path><path d=\"M41.69,47.66H39.16a1,1,0,0,0,0,2h2.53A1,1,0,0,0,41.69,47.66Z\" id=\"id_103\" style=\"fill: rgb(255, 255, 255);\"><\/path><path d=\"M55,47.66H45.2a1,1,0,0,0,0,2H55A1,1,0,0,0,55,47.66Z\" id=\"id_104\" style=\"fill: rgb(255, 255, 255);\"><\/path><\/g><\/svg><\/div>                  \n                    <div class=\"ue_info\">\n            <div class=\"ue_main\">Die Nagetiere<\/div>                                             <div class=\"ue_sub\"> <p>In der H\u00f6hle gibt es auch viele M\u00e4use, vor allem Ratten. Die \u00dcberreste ihrer Nahrung, wie z. B. Eichelschalen, sind, wenn sie verschimmelt sind, erstklassige Nahrung f\u00fcr h\u00f6hlenbewohnende Tiere, die Saprophyten.<\/p>\n <\/div>                                        <\/div>\n                      <\/div>\n      \n<\/div>\n<div id=\"uc_expanding_content_cards_elementor_a1dd6c2_item2\" class=\"ue_option elementor-repeater-item-dba24c4 \" style=\"background-image:url(https:\/\/sfentoni-cave.com\/wp-content\/uploads\/2023\/05\/grecaniscous-guanophilus-1-768x562.jpg);\">\n      <div class=\"ue_shadow\"><\/div>      <div class=\"ue_label\">\n         \n          <div class=\"ue_icon graphic_element_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 64 64\"><defs><style>.cls-1{fill:none;}.cls-1,.cls-2{stroke:#000;stroke-linecap:round;stroke-linejoin:round;stroke-width:2px;}.cls-2{fill:#bf7e68;}<\/style><\/defs><g id=\"scorpion\"><circle cx=\"9.93\" cy=\"49.4\" r=\"1.07\" id=\"id_101\" style=\"fill: rgb(255, 255, 255);\"><\/circle><circle cx=\"54.93\" cy=\"22.4\" r=\"1.07\" id=\"id_102\" style=\"fill: rgb(255, 255, 255);\"><\/circle><line class=\"cls-1\" x1=\"13\" y1=\"35\" x2=\"13\" y2=\"39\" id=\"id_103\" style=\"stroke: rgb(255, 255, 255);\"><\/line><line class=\"cls-1\" x1=\"11\" y1=\"37\" x2=\"15\" y2=\"37\" id=\"id_104\" style=\"stroke: rgb(255, 255, 255);\"><\/line><circle class=\"cls-1\" cx=\"19\" cy=\"53\" r=\"2\" id=\"id_105\" style=\"stroke: rgb(255, 255, 255);\"><\/circle><path class=\"cls-1\" d=\"M38.26,24.15a8.55,8.55,0,0,0,4.25-5\" id=\"id_106\" style=\"stroke: rgb(255, 255, 255);\"><\/path><path class=\"cls-1\" d=\"M46.4,20.11a12.7,12.7,0,0,1-6.69,7.8\" id=\"id_107\" style=\"stroke: rgb(255, 255, 255);\"><\/path><path class=\"cls-2\" d=\"M24.67,24.11a8.59,8.59,0,0,1-4.24-5.17\" id=\"id_108\" style=\"fill: rgb(255, 255, 255); stroke: rgb(255, 255, 255);\"><\/path><path class=\"cls-2\" d=\"M16.57,20a12.68,12.68,0,0,0,6.72,7.91\" id=\"id_109\" style=\"fill: rgb(255, 255, 255); stroke: rgb(255, 255, 255);\"><\/path><path class=\"cls-1\" d=\"M11.62.88c0,3.06,1.06,7.34,5.88,11.62a13.5,13.5,0,0,0,7.14-6.75A14.32,14.32,0,0,1,25,9c0,6.08-3.58,11-8,11S9,15.08,9,9A13.06,13.06,0,0,1,11.62.88Z\" id=\"id_110\" style=\"stroke: rgb(255, 255, 255);\"><\/path><line class=\"cls-1\" x1=\"22\" y1=\"22\" x2=\"20\" y2=\"25\" id=\"id_111\" style=\"stroke: rgb(255, 255, 255);\"><\/line><path class=\"cls-1\" d=\"M34,46.58V49a7,7,0,0,0,7,7c3.86,0,8-3.14,8-7V44\" id=\"id_112\" style=\"stroke: rgb(255, 255, 255);\"><\/path><path class=\"cls-1\" d=\"M53,44.43V49c0,7.17-4.83,13-12,13A13,13,0,0,1,28,49V45.93\" id=\"id_113\" style=\"stroke: rgb(255, 255, 255);\"><\/path><path class=\"cls-1\" d=\"M25.56,23A19.23,19.23,0,0,0,23,33c0,7.73,3.81,14,8.5,14S40,40.73,40,33a19.23,19.23,0,0,0-2.56-10Z\" id=\"id_114\" style=\"stroke: rgb(255, 255, 255);\"><\/path><line class=\"cls-1\" x1=\"41\" y1=\"22\" x2=\"43\" y2=\"25\" id=\"id_115\" style=\"stroke: rgb(255, 255, 255);\"><\/line><path class=\"cls-1\" d=\"M29,16s-4,1-.61,6.87\" id=\"id_116\" style=\"stroke: rgb(255, 255, 255);\"><\/path><path class=\"cls-1\" d=\"M34,16s4,1,.62,6.87\" id=\"id_117\" style=\"stroke: rgb(255, 255, 255);\"><\/path><circle cx=\"34.93\" cy=\"26.4\" r=\"1.07\" id=\"id_118\" style=\"fill: rgb(255, 255, 255);\"><\/circle><circle cx=\"27.93\" cy=\"26.4\" r=\"1.07\" id=\"id_119\" style=\"fill: rgb(255, 255, 255);\"><\/circle><line class=\"cls-1\" x1=\"34.08\" y1=\"50.8\" x2=\"28.73\" y2=\"52.81\" id=\"id_120\" style=\"stroke: rgb(255, 255, 255);\"><\/line><line class=\"cls-1\" x1=\"35.49\" y1=\"53.92\" x2=\"31.46\" y2=\"57.45\" id=\"id_121\" style=\"stroke: rgb(255, 255, 255);\"><\/line><line class=\"cls-1\" x1=\"38.36\" y1=\"55.89\" x2=\"36.29\" y2=\"60.88\" id=\"id_122\" style=\"stroke: rgb(255, 255, 255);\"><\/line><line class=\"cls-1\" x1=\"41.83\" y1=\"56.19\" x2=\"42.49\" y2=\"61.58\" id=\"id_123\" style=\"stroke: rgb(255, 255, 255);\"><\/line><line class=\"cls-1\" x1=\"45.41\" y1=\"54.98\" x2=\"48.08\" y2=\"59.36\" id=\"id_124\" style=\"stroke: rgb(255, 255, 255);\"><\/line><line class=\"cls-1\" x1=\"48.18\" y1=\"52.41\" x2=\"51.51\" y2=\"54.68\" id=\"id_125\" style=\"stroke: rgb(255, 255, 255);\"><\/line><line class=\"cls-1\" x1=\"49.39\" y1=\"48.68\" x2=\"52.47\" y2=\"49.04\" id=\"id_126\" style=\"stroke: rgb(255, 255, 255);\"><\/line><path class=\"cls-1\" d=\"M46.19,33.68s2.79-2.66,4,.67-2.39,6.12-1.86,8.38,4.52,2.8,5.72.27,1.73-10.78-2.26-12.38S46.19,33.68,46.19,33.68Z\" id=\"id_127\" style=\"stroke: rgb(255, 255, 255);\"><\/path><line class=\"cls-1\" x1=\"17.52\" y1=\"12.5\" x2=\"19.6\" y2=\"14.27\" id=\"id_128\" style=\"stroke: rgb(255, 255, 255);\"><\/line><path class=\"cls-1\" d=\"M51.38.88c0,3.06-1.06,7.34-5.88,11.62a13.5,13.5,0,0,1-7.14-6.75A14.32,14.32,0,0,0,38,9c0,6.08,3.58,11,8,11s8-4.92,8-11A13.06,13.06,0,0,0,51.38.88Z\" id=\"id_129\" style=\"stroke: rgb(255, 255, 255);\"><\/path><line class=\"cls-1\" x1=\"45.48\" y1=\"12.5\" x2=\"43.4\" y2=\"14.27\" id=\"id_130\" style=\"stroke: rgb(255, 255, 255);\"><\/line><\/g><\/svg><\/div>                  \n                    <div class=\"ue_info\">\n            <div class=\"ue_main\">Die wirbellosen Tiere<\/div>                                             <div class=\"ue_sub\"> <p>In der H\u00f6hle leben mehrere Arten wirbelloser Tiere. Die wichtigsten von ihnen sind Isopoden, Pseudoskorpione, Zweibeiner, Diptera und Schnecken. Sie alle sind winzig klein, schlank, farblos und blind. Keiner von ihnen kann in der freien Natur leben, da sie den Klimaver\u00e4nderungen nicht standhalten k\u00f6nnen. Sie nehmen ihre Umwelt mit ihren hochsensiblen taktilen und chemischen Sinnen wahr und k\u00f6nnen lange Zeitr\u00e4ume des Hungers \u00fcberstehen. Diese Arten haben eine sehr begrenzte geografische Verbreitung, sehr kleine Populationen und bilden die troglobische H\u00f6hlenwelt.<\/p>\n <\/div>                                        <\/div>\n                      <\/div>\n      \n<\/div>\n\n  <\/div>\n<\/div>\n<!-- end Expanding Content Cards -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5d5b502 e-con-full e-flex e-con e-parent\" data-id=\"5d5b502\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-225d272 e-con-full e-flex e-con e-child\" data-id=\"225d272\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3f51656 elementor-skin-carousel elementor-arrows-yes elementor-widget elementor-widget-media-carousel\" data-id=\"3f51656\" data-element_type=\"widget\" data-settings=\"{&quot;effect&quot;:&quot;fade&quot;,&quot;speed&quot;:1500,&quot;lazyload&quot;:&quot;yes&quot;,&quot;skin&quot;:&quot;carousel&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_widescreen&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slider\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"\u03b3\u03bb\u03c5\u03c0\u03c4\u03b9\u03ba\u03ae \u03c3\u03c4\u03bf \u03c3\u03ba\u03bf\u03c4\u03ac\u03b4\u03b9 1\" data-background=\"https:\/\/sfentoni-cave.com\/wp-content\/uploads\/2023\/05\/\u03b3\u03bb\u03c5\u03c0\u03c4\u03b9\u03ba\u03ae-\u03c3\u03c4\u03bf-\u03c3\u03ba\u03bf\u03c4\u03ac\u03b4\u03b9-1.jpg\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"\u03b3\u03bb\u03c5\u03c0\u03c4\u03b9\u03ba\u03ae \u03c3\u03c4\u03bf \u03c3\u03ba\u03bf\u03c4\u03ac\u03b4\u03b9 6\" data-background=\"https:\/\/sfentoni-cave.com\/wp-content\/uploads\/2023\/05\/\u03b3\u03bb\u03c5\u03c0\u03c4\u03b9\u03ba\u03ae-\u03c3\u03c4\u03bf-\u03c3\u03ba\u03bf\u03c4\u03ac\u03b4\u03b9-6.jpg\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"\u03b3\u03bb\u03c5\u03c0\u03c4\u03b9\u03ba\u03ae \u03c3\u03c4\u03bf \u03c3\u03ba\u03bf\u03c4\u03ac\u03b4\u03b9 9\" data-background=\"https:\/\/sfentoni-cave.com\/wp-content\/uploads\/2023\/05\/\u03b3\u03bb\u03c5\u03c0\u03c4\u03b9\u03ba\u03ae-\u03c3\u03c4\u03bf-\u03c3\u03ba\u03bf\u03c4\u03ac\u03b4\u03b9-9.jpg\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Voriger\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"N\u00e4chster\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f52ec9f e-con-full e-flex e-con e-child\" data-id=\"f52ec9f\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-8040761 animated-slow e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"8040761\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6700b18 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"6700b18\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Skulptur im Dunkeln<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-643281e elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"643281e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Stalaktiten und Stalagmiten<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61109ac elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"61109ac\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:800}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tief im Inneren der H\u00f6hle ver\u00e4ndert nur das Ger\u00e4usch der von der Decke fallenden Wassertropfen die ewige Monotonie der dunklen, stillen und feuchten Umgebung. Mit dem Tropfen und der langsamen Kristallisation der Wassersalze schafft die Natur Skulpturen von hoher \u00e4sthetischer Qualit\u00e4t. Wie seltsam ist es doch, dass dies in einem ewig dunklen Raum geschieht!<\/p>\n<p>Das Kalziumkarbonat, das sich im Wasser aufgel\u00f6st hat, als es durch die Risse im Kalksteinfelsen floss, kristallisiert am Rande eines Tropfens. Langsam bildet sich eine kleine zerbrechliche R\u00f6hre. Wenn es verstopft ist, beginnt das Wasser an seiner Au\u00dfenfl\u00e4che herunterzuflie\u00dfen. Wenn das Kalziumkarbonat im Destillierapparat auskristallisiert, bildet sich ein Stalaktit Stalagmiten bilden sich an den Aufschlagstellen der Tropfen. Es gibt eine unendliche Vielfalt an Gr\u00f6\u00dfen und Formen, die entstehen k\u00f6nnen. Wenn sogar Metalloxide im Wasser gel\u00f6st sind, f\u00e4rbt sich das Stalagmitenmaterial.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-80f8c06 e-con-full e-flex e-con e-parent\" data-id=\"80f8c06\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-3d7d1b1 e-con-full e-flex e-con e-child\" data-id=\"3d7d1b1\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-fd346c6 e-flex e-con-boxed e-con e-child\" data-id=\"fd346c6\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b765210 elementor-widget elementor-widget-heading\" data-id=\"b765210\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Stalaktit<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63468e5 elementor-widget elementor-widget-text-editor\" data-id=\"63468e5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Stalaktiten entstehen durch die Konzentration von Kalziumkarbonat w\u00e4hrend des Tropfens in den H\u00f6hlen. Je nach der Menge des vom Wasser mitgef\u00fchrten Kalziumkarbonats und je nach Flie\u00dfgeschwindigkeit des Wassers k\u00f6nnen sie sich innerhalb weniger Jahre oder sogar erst nach Jahrhunderten bilden. Die F\u00e4rbung der Stalaktiten stammt von verschiedenen Oxiden, und alle Stalaktiten haben einen kleinen Wassertropfen auf sich.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1077a35 e-con-full e-flex e-con e-child\" data-id=\"1077a35\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-b26cef0 e-flex e-con-boxed e-con e-child\" data-id=\"b26cef0\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-004aca2 elementor-widget elementor-widget-heading\" data-id=\"004aca2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Stalagmit<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-009c876 elementor-widget elementor-widget-text-editor\" data-id=\"009c876\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Der Stalagmit bildet sich unter dem Stalaktit an der Stelle, an der die Wassertropfen den Boden erreichen, daher ist die Geschwindigkeit seiner Bildung \u00e4hnlich der des Stalaktits. Stalagmiten bilden sich auf die gleiche Weise wie Stalaktiten aus dem restlichen Kalziumkarbonat, das der Wassertropfen beim Fallen auf den Boden mit sich f\u00fchrt. Der einzige Unterschied ist, dass ihr Wachstum vom Boden ausgeht.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2880c3d e-con-full e-flex e-con e-parent\" data-id=\"2880c3d\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b18e4db e-con-full e-flex e-con e-child\" data-id=\"b18e4db\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-45d35f3 e-flex e-con-boxed e-con e-child\" data-id=\"45d35f3\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ae4e473 elementor-widget elementor-widget-heading\" data-id=\"ae4e473\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kristalle <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fad3e02 elementor-widget elementor-widget-text-editor\" data-id=\"fad3e02\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Konzentration von Kalziumkarbonat f\u00fchrt zur Bildung von winzigen Kristallen, die leuchten. In der H\u00f6hle von Sfendoni ist dieses Glitzern in vielen Felsen der H\u00f6hle zu sehen und sorgt f\u00fcr einen spektakul\u00e4ren Effekt, so als h\u00e4tte jemand Goldstaub auf sie gestreut.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2159add e-con-full e-flex e-con e-child\" data-id=\"2159add\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-ce4817f e-flex e-con-boxed e-con e-child\" data-id=\"ce4817f\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c80cc5 elementor-widget elementor-widget-heading\" data-id=\"2c80cc5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Schwarze Punkte<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2390358 elementor-widget elementor-widget-text-editor\" data-id=\"2390358\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die schwarzen Punkte auf dem Dach einer H\u00f6hle sind die Ruhest\u00e4tten der Flederm\u00e4use. Die schwarze Farbe ist haupts\u00e4chlich auf ihren Atem, Talg (eine Art Schmiermittel in ihren Fl\u00fcgeln, das ihnen beim Fliegen hilft) und ihren Kot zur\u00fcckzuf\u00fchren.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aa0eb3f e-con-full e-flex e-con e-child\" data-id=\"aa0eb3f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-ac5c86c e-flex e-con-boxed e-con e-child\" data-id=\"ac5c86c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d12f81 elementor-widget elementor-widget-heading\" data-id=\"4d12f81\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">S\u00e4ulen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d97c15 elementor-widget elementor-widget-text-editor\" data-id=\"4d97c15\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Verbindung von Stalaktiten und Stalagmiten f\u00fchrt zur Bildung von S\u00e4ulen. Das sind beeindruckende Formationen, die mehrere Meter H\u00f6he erreichen k\u00f6nnen. In der Sfendoni-H\u00f6hle sehen Sie die gr\u00f6\u00dften S\u00e4ulen im \u201ePalast\u201c-Saal, w\u00e4hrend Sie im \u201eParthenon\u201c die symmetrischsten und wellenf\u00f6rmigsten sehen k\u00f6nnen.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Geschichten, Mythen und Geologie Die H\u00f6hle Die Sfendoni-H\u00f6hle am Fu\u00dfe des Psiloritis ist eine der gr\u00f6\u00dften nat\u00fcrlichen Architektursch\u00f6pfungen in Griechenland. In ihrem Inneren finden Sie Stalagmiten und Stalaktiten, die im Laufe der Jahre durch den Wasserfluss entstanden sind. Wenn Sie die H\u00f6hle besuchen, werden Sie die atemberaubende nat\u00fcrliche Sch\u00f6nheit Kretas entdecken. Sie ist vom Dorf [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2769","page","type-page","status-publish","hentry"],"rankMath":{"parentDomain":"sfentoni-cave.com","noFollowDomains":[],"noFollowExcludeDomains":[],"noFollowExternalLinks":false,"featuredImageNotice":"Das angezeigte Beitragsbild sollte mindestens 200x200 px gro\u00df sein, damit Facebook und andere Social-Media-Websites es \u00fcbernehmen.","pluginReviewed":true,"postSettings":{"linkSuggestions":true,"useFocusKeyword":false},"frontEndScore":false,"postName":"die-hohle","permalinkFormat":"https:\/\/sfentoni-cave.com\/de\/%pagename%\/","showLockModifiedDate":true,"assessor":{"focusKeywordLink":"https:\/\/sfentoni-cave.com\/wp-admin\/edit.php?focus_keyword=%focus_keyword%&post_type=%post_type%","hasTOCPlugin":true,"primaryTaxonomy":false,"serpData":{"title":"","description":"","focusKeywords":"","pillarContent":false,"canonicalUrl":"","breadcrumbTitle":"","advancedRobots":[],"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":"","facebookHasOverlay":false,"facebookImageOverlay":"","facebookAuthor":"","twitterCardType":"","twitterUseFacebook":true,"twitterTitle":"","twitterDescription":"","twitterImage":"","twitterImageID":"","twitterHasOverlay":false,"twitterImageOverlay":"","twitterPlayerUrl":"","twitterPlayerSize":"","twitterPlayerStream":"","twitterPlayerStreamCtype":"","twitterAppDescription":"","twitterAppIphoneName":"","twitterAppIphoneID":"","twitterAppIphoneUrl":"","twitterAppIpadName":"","twitterAppIpadID":"","twitterAppIpadUrl":"","twitterAppGoogleplayName":"","twitterAppGoogleplayID":"","twitterAppGoogleplayUrl":"","twitterAppCountry":"","robots":{"index":true},"twitterAuthor":"Benutzername","primaryTerm":0,"authorName":"renia","titleTemplate":"%title% %sep% %sitename%","descriptionTemplate":"%excerpt%","showScoreFrontend":true,"lockModifiedDate":false},"powerWords":["abgelenkt","abgesturzt","absolut","abstossend","aburd","abweisen","adaquat","aggressiv","ahnungslos","akkurat","alarmierend","alarmiert","albtraum","all-inclusive","allererste","allererster","allererstes","alleswisser","am schlechtesten","am wichtigsten","angewidert","angriff","angsteinflossend","angstlich","animiert","ankundigung","anonym","anpassbar","anspruchslos","anstossig","antagonistisch","apokalypse","applaus","argumentativ","arm","armageddon","arrogant","atemberaubend","attacke","attraktiv","aufdeckend","aufgebracht","aufgedeckt","aufgeregt","aufheiternd","aufregend","aufregende","aufregenden","aufregung","aufstachelnd","aufstandisch","aufsteigend","auftreibend","augenoffnend","ausgelassen","ausgeruht","ausgespielt","ausgewahlt","ausgewuhlt","ausnutzen","aussergewohnlich","autark","authentisch","autoritat","backdoor","badass","beangstigend","bedenklich","bedingungslos","bedrohen","bedroht","beforderung","befreit","befriedigend","befriedigt","begehren","begeistern","begeistert","begeisterung","beherzt","behind the scenes","beichte","beleidigung","belohnung","bemerkenswert","beneiden","bequem","beruhmt","beschadigen","beschamend","beschmutzt","beschuldigen","beschutzen","besitz","bessesen","bestatigen","bestatigt","beste","bestimmt","bestrafen","betrug","betrugen","bewahrt","bewiesen","bewiesenermassen","bewusst","bezahlbar","bezaubernd","bizarre","bleich","blendend","blut","blutbad","blutig","bombe","bonanza","bonus","bosartig","bose","boshaft","brilliant","brodelnd","brutal","budget","bullshit","bully","bunt","bunte","bunten","case study","cash","challenge","challgene","chaos","cheat-sheet","clever","content","cool","courage","dankbar","daruber redet keiner","deadline","definitiv","dekadent","demoralisierend","demut","desillusioniert","detailiert","diagnose","die wahrheit","direkt","disastros","discount","dokument","dollar","dominieren","doppelt","download","dreckig","dreifach","dreistigkeit","dringend","dringlichkeit","dumm","dummkopf","dummlich","durchbruch","duselig","dynamik","echt","effektiv","effizient","ehrlich","eier","eifersuchtig","eifrig","eindeutig","eindrucksvoll","eine stufe besser","einfach","einfachheit","einfallsreich","eingebildet","eingeschrankt","eingesperrt","einmalig","einsam","eintauchen","einzigartig","eisern","eliminieren","elite","empathie","empfehle","empfehlen","endeffekt","energie","energisch","enorm","entdecken","entfesselt","entfremdet","enthullen","enthullung","enthusiastisch","entmachtet","entsetzlich","entspannt","entzuckend","entzunden","epidemisch","episch","erbarmlich","erfolg","erfolgreich","erfolgsbilanz","erfreut","erfullen","erfullt","ergebnisse","ergreifen","erhaben","erheben","erhohen","erledigt","ermachtigt","ermudet","ernmutigt","ernsthaft","erobern","erroten","errungenschaft","erschaffen","erschrocken","ersehnen","ersparnisse","erstattbar","erstatten","erstaunlich","erste","ertrinken","essentiell","ethisch","euphorisch","exakt","exklusiv","exklusivitat","exkuisit","experte","explodieren","explosiv","exposed","extrem","exzellent","fahig","fahigkeiten","fail","falle","fantasie","fantastischen","farbenfroh","farbenfrohe","faszinierend","faszinierende","faul","faux pas","faux","fehler","feindselig","feldstudie","fesselnd","festlich","festmahl","festplatte","final","flirt","fluchtling","flussig","fokus","fokussiert","folter","formel","frech","freebie","frei","freiheit","freudig","friedlich","frohlich","frohlichkeit","frustriert","fundamental","fur immer","furchtbar","furchtlos","gangster","garantiert","geblendet","geehrt","gefahr","gefahrlich","gefangen","gefangnis","gefeuert","gegensatzlich","gehassig","geheimnis","geheimnisse","geil","geisseln","geist","geistesgestort","gelassen","geld zuruck","geld","genial","gepackt","gerade angekommen","gerissen","geschenk","geschmuggelt","geschutzt","gestandnis","gestandnisse","gestopft","gestresst","gesucht","gesund","getauscht","getestet","getotet","gewaltig","gewalttatig","gewidmet","gewinnspiel","gier","gierig","gift","giftig","gigantisch","giveaway","glamourose","glanzend","glaube","glaubwurdig","gleichmassig","glittering","glitzernde","gluckselig","golden","grandios","grandiose","grandiosen","grandioses","grauenhaft","grausamkeit","grinsen","groesste","gross","grossartig","grossartig","grossartige","grossartigen","grossartiger","grossartiges","grosse","grossen","grosste","grosszugig","grotesk","grube","grundlegend","gruselig","gunstig","hack","hamisch","hammer","handelsgeheimnis","hartnackig","hass","heilig","heimlich","heisshunger","heisshungrig","heiter","held","hell","herablassend","herausfordernd","herausforderung","herausvorderung","herrlichen","herrschend","hervorragend","herz","herzbrechend","herzerwahrmend","heute","hightech","hilflosigkeit","hilfreich","hilfsbereit","himmlisch","hinterhaltig","hoax","hocheffektiv","hochnasig","hochste","hoffnung","hoffnungsvoll","holle","holocaust","horror","how to","humor","hungrige","hurrikan","hypnotisch","hypnotisierend","idiot","idiotisch","illegal","immer","informativ","inhalt","inkompetent","innovativ","insider","inspirierend","inspiriert","intelligent","intensiv","interessant","interessante","invasion","investment","ist da","jackpot","jederzeit kundigen","jetzt","jubilant","jumpstart","jung","kadaver","kampf","katapult","katastrophe","kaufen","kein risiko","keine verpflichtung","kickstart","kindisch","kitschig","klaglich","klar","knast","kollabieren","kollosal","komfortabel","komisch","kompetitiv","komplett","kompromiss","komsich","konstruktiv","kontrollierend","kontrollverlust","kooperativ","kopie","korrupt","kostenlos","kraftlos","kraftvoll","krankhaft","kreativ","kreative","kriese","kritisch","kruppel","lachen","lacherlich","lahm","last minute","lauernd","lebendig","lebenslanglich","lecken","lecker","legendar","legitim","leiche","leicht","leiden","leider","leise","letzte chance","letzte","leuchtend","liberal","licht","liebe","liebenswurdig","liebevoll","life-changing","limitiert","lohnend","loser","losung","lugen","lugend","lukrativ","lust","lustig","lustige","lustigsten","luxorios","magisch","mainstream","mammut","manipulativ","massiv","masterclass","meditierend","meiseter","meistverkauft","meltdown","millionen","mind-blowing","minderwertig","minimalist","missbrauch","misstrauisch","mittelmassig","mittig","modern","moderne","moglichkeiten","monetarisieren","monumental","mord","motiviert","muhelos","muhevoll","mull","mut","mutig","nachmachen","nachteile","nackt","nagel","naiv","natural","nazi","neid","nervos","neu","niedertrachtig","niemals","notfall","notiert","nutzlich","nutzlos","offensichtlich","offiziel","offnen","ohne hintergedanken","ok","okay","okonomisch","on-demand","opfer","optimistisch","overnight","packend","panik","panzer","paralisiert","pas","passioniert","pause","payback","peinlich","perfekt","perplex","perskeptive","pessimistisch","pfund","piranha","pleite","plotzlich","pochend","polarisierend","popular","portfolio","praktisch","preis","prestige","privat","privatsphare","priviligiert","problem","produktiv","professionell","profit","profitabel","provokativ","provozierend","prozess","psychologisch","qual","qualen","qualitat","rabatt","rache","rachsuchtig","raffiniert","rasend","rat","rau","recherche","reduziert","reflektieren","regeln","reich","reiche","reichtum","relaxed","report","responsive","revolutionar","riesig","risiko","riskant","riskieren","rotzfrech","rowdy","ruckrat","ruckschlag","rucksichtlos","ruhig","ruiniert","sabotiert","sadistisch","sale","sarkastisch","scam","schabig","schadigend","schadlich","schamlos","schatz","schicksal","schlachten","schlafen","schlag","schlau","schlimm","schmerzhaft","schmerzlos","schmuggel","schnell","schnellstart","schokierend","schonheit","schrecklich","schreien","schritt fur schritt","schuld","schuldlos","schwach","schwarm","schwarzmarkt","schwerkraft","schwinden","sechsstellig","sehenswerte","selbsthass","selten","sensationell","sex","sexy","sicher","sicherheit","sicherlich","sieg","sill","simpel","sinnlich","sinnlos","skandal","skandalos","skill","sklave","sneak-peek","snob","sofort gespart","sofort","sollte","sonnig","sonnige","sonnigen","sorgen","sorgfaltig","sorglos","spannend","sparen","sparsam","spass","spassig","spektakular","speziell","spielen","spoiler","spontan","spotlight","stabil","stark","start","stoisch","stolz","stop","strahlend","strangulieren","strategie","studien","stumperhaft","stur","sunden","sundigend","super","superb","survival","tapfer","tauschend","teaser","technologie","terror","terrorist","teuer","tief","tiefgreifend","tierisch","tod","todlich","toll","tolle","toller","tortur","tot","tote","toten","totend","toxisch","tragisch","tragodie","transfomieren","transparenz","trauma","traumatisiert","traurigkeit","trend","tricks","trigger","triumpf","trocken","trotz","trugerisch","tweaks","tyrann","ubel","uberfordert","uberkommen","uberleben","uberlegen","uberraschend","uberrascht","uberraschung","uberwaltigend","uberwinden","ultimativ","umfassend","umstritten","umwerfend","unatorisiert","unaufhaltbar","unausgelasted","unbedacht","unbeliebt","unbeschwert","unbewusst","undercover","undokumentiert","unehrlich","unentschlossen","unerwartet","unfahig","ungeduldig","ungedult","ungehort","ungemutlich","ungerechtfertigt","ungesehen","ungetrubt","ungewohnlich","ungezogen","unglaublich","unglaubliches","uninteressiert","unkontrollierbar","unkonventionell","unlimitiert","unpenetrierbar","unschuldig","unsicher","unstabil","unter verschluss","untergrund","unterhaltsam","unterstutz","unterstutzend","unubertroffen","unvergesslich","unverneinbar","unvoreingenommen","unwiderstehlich","unwirtlich","unzensiert","unzuverlassig","up-selling","vaporisieren","verangstigt","verantwortlich","verargert","verarscht","verbessert","verbluffend","verblufft","verboten","verbreiten","verdachtig","verdammt","verdeckt","vereinfacht","verfuhrend","vergebend","vergessen","vergleich","verhauen","verifizieren","verkommen","verlegen","verletzbar","verletzt","verlockend","verloren","vermasselt","vermeiden","vermogen","vernichten","vernichtend","vernunftig","veroffentlichung","verpassen","verraterisch","verruckt","versagen","verschwitzt","versichert","verspielt","versprechend","versteckt","vertrauenswurdig","vertraulich","vertraumt","verurteilend","verwunderlich","verwundet","verzaubernd","verzweifelt","vierfach","vogelfrei","vollig","vollstandig","vorsicht","vorstellungskraft","vorteil","wachstum","wagemutig","wahnsinn","wahnsinnig","wahrhaftig","wahrheit","wahrheitsgemass","wahrscheinlich","warnung","was dir keiner sagt","wehleidig","welt","wenig bekannt","wert","wertvoll","wichtig","widerlich","wiedererkannt","wild","wilde","wilden","willensstarke","wirr","wohltatigkeit","wortlich","wunder","wunderbar","wunderbaren","wunderschon","wutend","zeichen","zeitig","zen","zensiert","zerschlagen","zerschmetternd","zerstorend","zertifiziert","zielorientiert","zischend","zischt","zocken","zogernd","zugeben","zuruckgehalten","zuruckgelassen","zuruckweisen","zusatzlich","zutaten","zuverlassig","zwangsernahrt","zweifelnd","zwickend","zwingend","einfache","einfachen","einfaches","einfacher","simple","simplen","simples","simpler","besten","bestes","bester","beste","bestbewertet","bestbewerteten","bestbewertete","bestbewerteter","bestbewertetes","\u00fcberraschende","\u00fcberraschenden","\u00fcberraschendes","\u00fcberraschender","hilfreiche","hilfreiches","hilfreichen","hilfreicher","f\u00f6rdern","unterst\u00fctzen","helfen","spielerisch","spannende","spannendes","spannenden","spannender","gro\u00dfartige","gro\u00dfartiges","gro\u00dfartigen","gro\u00dfartiger","ideal","ideales","idealen","idealer","faszinierend","faszinierendes","faszinierenden","faszinierender","wichtig","wichtige","wichtiges","wichtigen","wichtiger","sicher","sichere","sicheres","sicheren","sicherer","umfassende","umfassendes","umfassenden","umfassender","ultimative","ultimatives","ultimativen","ultimativer","einzigartige","einzigartiges","einzigartigen","einzigartiger"],"diacritics":{"A":"[\\u0041\\u24B6\\uFF21\\u00C0\\u00C1\\u00C2\\u1EA6\\u1EA4\\u1EAA\\u1EA8\\u00C3\\u0100\\u0102\\u1EB0\\u1EAE\\u1EB4\\u1EB2\\u0226\\u01E0\\u01DE\\u1EA2\\u00C5\\u01FA\\u01CD\\u0200\\u0202\\u1EA0\\u1EAC\\u1EB6\\u1E00\\u0104\\u023A\\u2C6F]","AA":"[\\uA732]","AE":"[\\u00C6\\u01FC\\u01E2\\u00C4]","AO":"[\\uA734]","AU":"[\\uA736]","AV":"[\\uA738\\uA73A]","AY":"[\\uA73C]","B":"[\\u0042\\u24B7\\uFF22\\u1E02\\u1E04\\u1E06\\u0243\\u0182\\u0181]","C":"[\\u0043\\u24B8\\uFF23\\u0106\\u0108\\u010A\\u010C\\u00C7\\u1E08\\u0187\\u023B\\uA73E]","D":"[\\u0044\\u24B9\\uFF24\\u1E0A\\u010E\\u1E0C\\u1E10\\u1E12\\u1E0E\\u0110\\u018B\\u018A\\u0189\\uA779]","DZ":"[\\u01F1\\u01C4]","Dz":"[\\u01F2\\u01C5]","E":"[\\u0045\\u24BA\\uFF25\\u00C8\\u00C9\\u00CA\\u1EC0\\u1EBE\\u1EC4\\u1EC2\\u1EBC\\u0112\\u1E14\\u1E16\\u0114\\u0116\\u00CB\\u1EBA\\u011A\\u0204\\u0206\\u1EB8\\u1EC6\\u0228\\u1E1C\\u0118\\u1E18\\u1E1A\\u0190\\u018E]","F":"[\\u0046\\u24BB\\uFF26\\u1E1E\\u0191\\uA77B]","G":"[\\u0047\\u24BC\\uFF27\\u01F4\\u011C\\u1E20\\u011E\\u0120\\u01E6\\u0122\\u01E4\\u0193\\uA7A0\\uA77D\\uA77E]","H":"[\\u0048\\u24BD\\uFF28\\u0124\\u1E22\\u1E26\\u021E\\u1E24\\u1E28\\u1E2A\\u0126\\u2C67\\u2C75\\uA78D]","I":"[\\u0049\\u24BE\\uFF29\\u00CC\\u00CD\\u00CE\\u0128\\u012A\\u012C\\u0130\\u00CF\\u1E2E\\u1EC8\\u01CF\\u0208\\u020A\\u1ECA\\u012E\\u1E2C\\u0197]","J":"[\\u004A\\u24BF\\uFF2A\\u0134\\u0248]","K":"[\\u004B\\u24C0\\uFF2B\\u1E30\\u01E8\\u1E32\\u0136\\u1E34\\u0198\\u2C69\\uA740\\uA742\\uA744\\uA7A2]","L":"[\\u004C\\u24C1\\uFF2C\\u013F\\u0139\\u013D\\u1E36\\u1E38\\u013B\\u1E3C\\u1E3A\\u0141\\u023D\\u2C62\\u2C60\\uA748\\uA746\\uA780]","LJ":"[\\u01C7]","Lj":"[\\u01C8]","M":"[\\u004D\\u24C2\\uFF2D\\u1E3E\\u1E40\\u1E42\\u2C6E\\u019C]","N":"[\\u004E\\u24C3\\uFF2E\\u01F8\\u0143\\u00D1\\u1E44\\u0147\\u1E46\\u0145\\u1E4A\\u1E48\\u0220\\u019D\\uA790\\uA7A4]","NJ":"[\\u01CA]","Nj":"[\\u01CB]","O":"[\\u004F\\u24C4\\uFF2F\\u00D2\\u00D3\\u00D4\\u1ED2\\u1ED0\\u1ED6\\u1ED4\\u00D5\\u1E4C\\u022C\\u1E4E\\u014C\\u1E50\\u1E52\\u014E\\u022E\\u0230\\u022A\\u1ECE\\u0150\\u01D1\\u020C\\u020E\\u01A0\\u1EDC\\u1EDA\\u1EE0\\u1EDE\\u1EE2\\u1ECC\\u1ED8\\u01EA\\u01EC\\u00D8\\u01FE\\u0186\\u019F\\uA74A\\uA74C]","OE":"[\\u00D6]","OI":"[\\u01A2]","OO":"[\\uA74E]","OU":"[\\u0222]","P":"[\\u0050\\u24C5\\uFF30\\u1E54\\u1E56\\u01A4\\u2C63\\uA750\\uA752\\uA754]","Q":"[\\u0051\\u24C6\\uFF31\\uA756\\uA758\\u024A]","R":"[\\u0052\\u24C7\\uFF32\\u0154\\u1E58\\u0158\\u0210\\u0212\\u1E5A\\u1E5C\\u0156\\u1E5E\\u024C\\u2C64\\uA75A\\uA7A6\\uA782]","S":"[\\u0053\\u24C8\\uFF33\\u1E9E\\u015A\\u1E64\\u015C\\u1E60\\u0160\\u1E66\\u1E62\\u1E68\\u0218\\u015E\\u2C7E\\uA7A8\\uA784]","T":"[\\u0054\\u24C9\\uFF34\\u1E6A\\u0164\\u1E6C\\u021A\\u0162\\u1E70\\u1E6E\\u0166\\u01AC\\u01AE\\u023E\\uA786]","TZ":"[\\uA728]","U":"[\\u0055\\u24CA\\uFF35\\u00D9\\u00DA\\u00DB\\u0168\\u1E78\\u016A\\u1E7A\\u016C\\u01DB\\u01D7\\u01D5\\u01D9\\u1EE6\\u016E\\u0170\\u01D3\\u0214\\u0216\\u01AF\\u1EEA\\u1EE8\\u1EEE\\u1EEC\\u1EF0\\u1EE4\\u1E72\\u0172\\u1E76\\u1E74\\u0244]","UE":"[\\u00DC]","V":"[\\u0056\\u24CB\\uFF36\\u1E7C\\u1E7E\\u01B2\\uA75E\\u0245]","VY":"[\\uA760]","W":"[\\u0057\\u24CC\\uFF37\\u1E80\\u1E82\\u0174\\u1E86\\u1E84\\u1E88\\u2C72]","X":"[\\u0058\\u24CD\\uFF38\\u1E8A\\u1E8C]","Y":"[\\u0059\\u24CE\\uFF39\\u1EF2\\u00DD\\u0176\\u1EF8\\u0232\\u1E8E\\u0178\\u1EF6\\u1EF4\\u01B3\\u024E\\u1EFE]","Z":"[\\u005A\\u24CF\\uFF3A\\u0179\\u1E90\\u017B\\u017D\\u1E92\\u1E94\\u01B5\\u0224\\u2C7F\\u2C6B\\uA762]","a":"[\\u0061\\u24D0\\uFF41\\u1E9A\\u00E0\\u00E1\\u00E2\\u1EA7\\u1EA5\\u1EAB\\u1EA9\\u00E3\\u0101\\u0103\\u1EB1\\u1EAF\\u1EB5\\u1EB3\\u0227\\u01E1\\u01DF\\u1EA3\\u00E5\\u01FB\\u01CE\\u0201\\u0203\\u1EA1\\u1EAD\\u1EB7\\u1E01\\u0105\\u2C65\\u0250]","aa":"[\\uA733]","ae":"[\\u00E6\\u01FD\\u01E3\\u00E4]","ao":"[\\uA735]","au":"[\\uA737]","av":"[\\uA739\\uA73B]","ay":"[\\uA73D]","b":"[\\u0062\\u24D1\\uFF42\\u1E03\\u1E05\\u1E07\\u0180\\u0183\\u0253]","c":"[\\u0063\\u24D2\\uFF43\\u0107\\u0109\\u010B\\u010D\\u00E7\\u1E09\\u0188\\u023C\\uA73F\\u2184]","d":"[\\u0064\\u24D3\\uFF44\\u1E0B\\u010F\\u1E0D\\u1E11\\u1E13\\u1E0F\\u0111\\u018C\\u0256\\u0257\\uA77A]","dz":"[\\u01F3\\u01C6]","e":"[\\u0065\\u24D4\\uFF45\\u00E8\\u00E9\\u00EA\\u1EC1\\u1EBF\\u1EC5\\u1EC3\\u1EBD\\u0113\\u1E15\\u1E17\\u0115\\u0117\\u00EB\\u1EBB\\u011B\\u0205\\u0207\\u1EB9\\u1EC7\\u0229\\u1E1D\\u0119\\u1E19\\u1E1B\\u0247\\u025B\\u01DD]","f":"[\\u0066\\u24D5\\uFF46\\u1E1F\\u0192\\uA77C]","g":"[\\u0067\\u24D6\\uFF47\\u01F5\\u011D\\u1E21\\u011F\\u0121\\u01E7\\u0123\\u01E5\\u0260\\uA7A1\\u1D79\\uA77F]","h":"[\\u0068\\u24D7\\uFF48\\u0125\\u1E23\\u1E27\\u021F\\u1E25\\u1E29\\u1E2B\\u1E96\\u0127\\u2C68\\u2C76\\u0265]","hv":"[\\u0195]","i":"[\\u0069\\u24D8\\uFF49\\u00EC\\u00ED\\u00EE\\u0129\\u012B\\u012D\\u00EF\\u1E2F\\u1EC9\\u01D0\\u0209\\u020B\\u1ECB\\u012F\\u1E2D\\u0268\\u0131]","j":"[\\u006A\\u24D9\\uFF4A\\u0135\\u01F0\\u0249]","k":"[\\u006B\\u24DA\\uFF4B\\u1E31\\u01E9\\u1E33\\u0137\\u1E35\\u0199\\u2C6A\\uA741\\uA743\\uA745\\uA7A3]","l":"[\\u006C\\u24DB\\uFF4C\\u0140\\u013A\\u013E\\u1E37\\u1E39\\u013C\\u1E3D\\u1E3B\\u017F\\u0142\\u019A\\u026B\\u2C61\\uA749\\uA781\\uA747]","lj":"[\\u01C9]","m":"[\\u006D\\u24DC\\uFF4D\\u1E3F\\u1E41\\u1E43\\u0271\\u026F]","n":"[\\u006E\\u24DD\\uFF4E\\u01F9\\u0144\\u00F1\\u1E45\\u0148\\u1E47\\u0146\\u1E4B\\u1E49\\u019E\\u0272\\u0149\\uA791\\uA7A5]","nj":"[\\u01CC]","o":"[\\u006F\\u24DE\\uFF4F\\u00F2\\u00F3\\u00F4\\u1ED3\\u1ED1\\u1ED7\\u1ED5\\u00F5\\u1E4D\\u022D\\u1E4F\\u014D\\u1E51\\u1E53\\u014F\\u022F\\u0231\\u022B\\u1ECF\\u0151\\u01D2\\u020D\\u020F\\u01A1\\u1EDD\\u1EDB\\u1EE1\\u1EDF\\u1EE3\\u1ECD\\u1ED9\\u01EB\\u01ED\\u00F8\\u01FF\\u0254\\uA74B\\uA74D\\u0275]","oe":"[\\u00f6]","oi":"[\\u01A3]","ou":"[\\u0223]","oo":"[\\uA74F]","p":"[\\u0070\\u24DF\\uFF50\\u1E55\\u1E57\\u01A5\\u1D7D\\uA751\\uA753\\uA755]","q":"[\\u0071\\u24E0\\uFF51\\u024B\\uA757\\uA759]","r":"[\\u0072\\u24E1\\uFF52\\u0155\\u1E59\\u0159\\u0211\\u0213\\u1E5B\\u1E5D\\u0157\\u1E5F\\u024D\\u027D\\uA75B\\uA7A7\\uA783]","s":"[\\u0073\\u24E2\\uFF53\\u015B\\u1E65\\u015D\\u1E61\\u0161\\u1E67\\u1E63\\u1E69\\u0219\\u015F\\u023F\\uA7A9\\uA785\\u1E9B]","ss":"[\\u00DF]","t":"[\\u0074\\u24E3\\uFF54\\u1E6B\\u1E97\\u0165\\u1E6D\\u021B\\u0163\\u1E71\\u1E6F\\u0167\\u01AD\\u0288\\u2C66\\uA787]","tz":"[\\uA729]","u":"[\\u0075\\u24E4\\uFF55\\u00F9\\u00FA\\u00FB\\u0169\\u1E79\\u016B\\u1E7B\\u016D\\u01DC\\u01D8\\u01D6\\u01DA\\u1EE7\\u016F\\u0171\\u01D4\\u0215\\u0217\\u01B0\\u1EEB\\u1EE9\\u1EEF\\u1EED\\u1EF1\\u1EE5\\u1E73\\u0173\\u1E77\\u1E75\\u0289]","ue":"[\\u00FC]","v":"[\\u0076\\u24E5\\uFF56\\u1E7D\\u1E7F\\u028B\\uA75F\\u028C]","vy":"[\\uA761]","w":"[\\u0077\\u24E6\\uFF57\\u1E81\\u1E83\\u0175\\u1E87\\u1E85\\u1E98\\u1E89\\u2C73]","x":"[\\u0078\\u24E7\\uFF58\\u1E8B\\u1E8D]","y":"[\\u0079\\u24E8\\uFF59\\u1EF3\\u00FD\\u0177\\u1EF9\\u0233\\u1E8F\\u00FF\\u1EF7\\u1E99\\u1EF5\\u01B4\\u024F\\u1EFF]","z":"[\\u007A\\u24E9\\uFF5A\\u017A\\u1E91\\u017C\\u017E\\u1E93\\u1E95\\u01B6\\u0225\\u0240\\u2C6C\\uA763]"},"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasRedirection":false,"hasBreadcrumb":false},"homeUrl":"https:\/\/sfentoni-cave.com\/de\/","objectID":2769,"objectType":"post","locale":"de","localeFull":"de_DE","overlayImages":{"play":{"name":"Wiedergabezeichen","url":"https:\/\/sfentoni-cave.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","path":"\/home\/u635043605\/domains\/sfentoni-cave.com\/public_html\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","position":"middle_center"},"gif":{"name":"GIF-Symbol","url":"https:\/\/sfentoni-cave.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","path":"\/home\/u635043605\/domains\/sfentoni-cave.com\/public_html\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","position":"middle_center"}},"defautOgImage":"https:\/\/sfentoni-cave.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/social-placeholder.jpg","customPermalinks":true,"isUserRegistered":true,"autoSuggestKeywords":true,"connectSiteUrl":"https:\/\/rankmath.com\/auth?site=https%3A%2F%2Fsfentoni-cave.com%2Fde%2F&r=https%3A%2F%2Fsfentoni-cave.com%2Fde%2Fwp-json%2Fwp%2Fv2%2Fpages%2F2769%3Fnonce%3D8fde0b3596","maxTags":5,"trendsIcon":"<svg viewBox=\"0 0 610 610\"><path d=\"M18.85,446,174.32,290.48l58.08,58.08L76.93,504a14.54,14.54,0,0,1-20.55,0L18.83,466.48a14.54,14.54,0,0,1,0-20.55Z\" style=\"fill:#4285f4\"\/><path d=\"M242.65,242.66,377.59,377.6l-47.75,47.75a14.54,14.54,0,0,1-20.55,0L174.37,290.43l47.75-47.75A14.52,14.52,0,0,1,242.65,242.66Z\" style=\"fill:#ea4335\"\/><polygon points=\"319.53 319.53 479.26 159.8 537.34 217.88 377.61 377.62 319.53 319.53\" style=\"fill:#fabb05\"\/><path d=\"M594.26,262.73V118.61h0a16.94,16.94,0,0,0-16.94-16.94H433.2a16.94,16.94,0,0,0-12,28.92L565.34,274.71h0a16.94,16.94,0,0,0,28.92-12Z\" style=\"fill:#34a853\"\/><rect width=\"610\" height=\"610\" style=\"fill:none\"\/><\/svg>","showScore":true,"siteFavIcon":"https:\/\/sfentoni-cave.com\/wp-content\/uploads\/2022\/09\/fav-150x150.jpg","canUser":{"general":false,"advanced":false,"snippet":false,"social":false,"analysis":false,"analytics":false,"content_ai":false},"isPro":false,"is_front_page":false,"trendsUpgradeLink":"https:\/\/rankmath.com\/pricing\/?utm_source=Plugin&utm_medium=CE%20General%20Tab%20Trends&utm_campaign=WP","trendsUpgradeLabel":"Upgraden","trendsPreviewImage":"https:\/\/sfentoni-cave.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/trends-preview.jpg","currentEditor":false,"homepageData":{"assessor":{"powerWords":["abgelenkt","abgesturzt","absolut","abstossend","aburd","abweisen","adaquat","aggressiv","ahnungslos","akkurat","alarmierend","alarmiert","albtraum","all-inclusive","allererste","allererster","allererstes","alleswisser","am schlechtesten","am wichtigsten","angewidert","angriff","angsteinflossend","angstlich","animiert","ankundigung","anonym","anpassbar","anspruchslos","anstossig","antagonistisch","apokalypse","applaus","argumentativ","arm","armageddon","arrogant","atemberaubend","attacke","attraktiv","aufdeckend","aufgebracht","aufgedeckt","aufgeregt","aufheiternd","aufregend","aufregende","aufregenden","aufregung","aufstachelnd","aufstandisch","aufsteigend","auftreibend","augenoffnend","ausgelassen","ausgeruht","ausgespielt","ausgewahlt","ausgewuhlt","ausnutzen","aussergewohnlich","autark","authentisch","autoritat","backdoor","badass","beangstigend","bedenklich","bedingungslos","bedrohen","bedroht","beforderung","befreit","befriedigend","befriedigt","begehren","begeistern","begeistert","begeisterung","beherzt","behind the scenes","beichte","beleidigung","belohnung","bemerkenswert","beneiden","bequem","beruhmt","beschadigen","beschamend","beschmutzt","beschuldigen","beschutzen","besitz","bessesen","bestatigen","bestatigt","beste","bestimmt","bestrafen","betrug","betrugen","bewahrt","bewiesen","bewiesenermassen","bewusst","bezahlbar","bezaubernd","bizarre","bleich","blendend","blut","blutbad","blutig","bombe","bonanza","bonus","bosartig","bose","boshaft","brilliant","brodelnd","brutal","budget","bullshit","bully","bunt","bunte","bunten","case study","cash","challenge","challgene","chaos","cheat-sheet","clever","content","cool","courage","dankbar","daruber redet keiner","deadline","definitiv","dekadent","demoralisierend","demut","desillusioniert","detailiert","diagnose","die wahrheit","direkt","disastros","discount","dokument","dollar","dominieren","doppelt","download","dreckig","dreifach","dreistigkeit","dringend","dringlichkeit","dumm","dummkopf","dummlich","durchbruch","duselig","dynamik","echt","effektiv","effizient","ehrlich","eier","eifersuchtig","eifrig","eindeutig","eindrucksvoll","eine stufe besser","einfach","einfachheit","einfallsreich","eingebildet","eingeschrankt","eingesperrt","einmalig","einsam","eintauchen","einzigartig","eisern","eliminieren","elite","empathie","empfehle","empfehlen","endeffekt","energie","energisch","enorm","entdecken","entfesselt","entfremdet","enthullen","enthullung","enthusiastisch","entmachtet","entsetzlich","entspannt","entzuckend","entzunden","epidemisch","episch","erbarmlich","erfolg","erfolgreich","erfolgsbilanz","erfreut","erfullen","erfullt","ergebnisse","ergreifen","erhaben","erheben","erhohen","erledigt","ermachtigt","ermudet","ernmutigt","ernsthaft","erobern","erroten","errungenschaft","erschaffen","erschrocken","ersehnen","ersparnisse","erstattbar","erstatten","erstaunlich","erste","ertrinken","essentiell","ethisch","euphorisch","exakt","exklusiv","exklusivitat","exkuisit","experte","explodieren","explosiv","exposed","extrem","exzellent","fahig","fahigkeiten","fail","falle","fantasie","fantastischen","farbenfroh","farbenfrohe","faszinierend","faszinierende","faul","faux pas","faux","fehler","feindselig","feldstudie","fesselnd","festlich","festmahl","festplatte","final","flirt","fluchtling","flussig","fokus","fokussiert","folter","formel","frech","freebie","frei","freiheit","freudig","friedlich","frohlich","frohlichkeit","frustriert","fundamental","fur immer","furchtbar","furchtlos","gangster","garantiert","geblendet","geehrt","gefahr","gefahrlich","gefangen","gefangnis","gefeuert","gegensatzlich","gehassig","geheimnis","geheimnisse","geil","geisseln","geist","geistesgestort","gelassen","geld zuruck","geld","genial","gepackt","gerade angekommen","gerissen","geschenk","geschmuggelt","geschutzt","gestandnis","gestandnisse","gestopft","gestresst","gesucht","gesund","getauscht","getestet","getotet","gewaltig","gewalttatig","gewidmet","gewinnspiel","gier","gierig","gift","giftig","gigantisch","giveaway","glamourose","glanzend","glaube","glaubwurdig","gleichmassig","glittering","glitzernde","gluckselig","golden","grandios","grandiose","grandiosen","grandioses","grauenhaft","grausamkeit","grinsen","groesste","gross","grossartig","grossartig","grossartige","grossartigen","grossartiger","grossartiges","grosse","grossen","grosste","grosszugig","grotesk","grube","grundlegend","gruselig","gunstig","hack","hamisch","hammer","handelsgeheimnis","hartnackig","hass","heilig","heimlich","heisshunger","heisshungrig","heiter","held","hell","herablassend","herausfordernd","herausforderung","herausvorderung","herrlichen","herrschend","hervorragend","herz","herzbrechend","herzerwahrmend","heute","hightech","hilflosigkeit","hilfreich","hilfsbereit","himmlisch","hinterhaltig","hoax","hocheffektiv","hochnasig","hochste","hoffnung","hoffnungsvoll","holle","holocaust","horror","how to","humor","hungrige","hurrikan","hypnotisch","hypnotisierend","idiot","idiotisch","illegal","immer","informativ","inhalt","inkompetent","innovativ","insider","inspirierend","inspiriert","intelligent","intensiv","interessant","interessante","invasion","investment","ist da","jackpot","jederzeit kundigen","jetzt","jubilant","jumpstart","jung","kadaver","kampf","katapult","katastrophe","kaufen","kein risiko","keine verpflichtung","kickstart","kindisch","kitschig","klaglich","klar","knast","kollabieren","kollosal","komfortabel","komisch","kompetitiv","komplett","kompromiss","komsich","konstruktiv","kontrollierend","kontrollverlust","kooperativ","kopie","korrupt","kostenlos","kraftlos","kraftvoll","krankhaft","kreativ","kreative","kriese","kritisch","kruppel","lachen","lacherlich","lahm","last minute","lauernd","lebendig","lebenslanglich","lecken","lecker","legendar","legitim","leiche","leicht","leiden","leider","leise","letzte chance","letzte","leuchtend","liberal","licht","liebe","liebenswurdig","liebevoll","life-changing","limitiert","lohnend","loser","losung","lugen","lugend","lukrativ","lust","lustig","lustige","lustigsten","luxorios","magisch","mainstream","mammut","manipulativ","massiv","masterclass","meditierend","meiseter","meistverkauft","meltdown","millionen","mind-blowing","minderwertig","minimalist","missbrauch","misstrauisch","mittelmassig","mittig","modern","moderne","moglichkeiten","monetarisieren","monumental","mord","motiviert","muhelos","muhevoll","mull","mut","mutig","nachmachen","nachteile","nackt","nagel","naiv","natural","nazi","neid","nervos","neu","niedertrachtig","niemals","notfall","notiert","nutzlich","nutzlos","offensichtlich","offiziel","offnen","ohne hintergedanken","ok","okay","okonomisch","on-demand","opfer","optimistisch","overnight","packend","panik","panzer","paralisiert","pas","passioniert","pause","payback","peinlich","perfekt","perplex","perskeptive","pessimistisch","pfund","piranha","pleite","plotzlich","pochend","polarisierend","popular","portfolio","praktisch","preis","prestige","privat","privatsphare","priviligiert","problem","produktiv","professionell","profit","profitabel","provokativ","provozierend","prozess","psychologisch","qual","qualen","qualitat","rabatt","rache","rachsuchtig","raffiniert","rasend","rat","rau","recherche","reduziert","reflektieren","regeln","reich","reiche","reichtum","relaxed","report","responsive","revolutionar","riesig","risiko","riskant","riskieren","rotzfrech","rowdy","ruckrat","ruckschlag","rucksichtlos","ruhig","ruiniert","sabotiert","sadistisch","sale","sarkastisch","scam","schabig","schadigend","schadlich","schamlos","schatz","schicksal","schlachten","schlafen","schlag","schlau","schlimm","schmerzhaft","schmerzlos","schmuggel","schnell","schnellstart","schokierend","schonheit","schrecklich","schreien","schritt fur schritt","schuld","schuldlos","schwach","schwarm","schwarzmarkt","schwerkraft","schwinden","sechsstellig","sehenswerte","selbsthass","selten","sensationell","sex","sexy","sicher","sicherheit","sicherlich","sieg","sill","simpel","sinnlich","sinnlos","skandal","skandalos","skill","sklave","sneak-peek","snob","sofort gespart","sofort","sollte","sonnig","sonnige","sonnigen","sorgen","sorgfaltig","sorglos","spannend","sparen","sparsam","spass","spassig","spektakular","speziell","spielen","spoiler","spontan","spotlight","stabil","stark","start","stoisch","stolz","stop","strahlend","strangulieren","strategie","studien","stumperhaft","stur","sunden","sundigend","super","superb","survival","tapfer","tauschend","teaser","technologie","terror","terrorist","teuer","tief","tiefgreifend","tierisch","tod","todlich","toll","tolle","toller","tortur","tot","tote","toten","totend","toxisch","tragisch","tragodie","transfomieren","transparenz","trauma","traumatisiert","traurigkeit","trend","tricks","trigger","triumpf","trocken","trotz","trugerisch","tweaks","tyrann","ubel","uberfordert","uberkommen","uberleben","uberlegen","uberraschend","uberrascht","uberraschung","uberwaltigend","uberwinden","ultimativ","umfassend","umstritten","umwerfend","unatorisiert","unaufhaltbar","unausgelasted","unbedacht","unbeliebt","unbeschwert","unbewusst","undercover","undokumentiert","unehrlich","unentschlossen","unerwartet","unfahig","ungeduldig","ungedult","ungehort","ungemutlich","ungerechtfertigt","ungesehen","ungetrubt","ungewohnlich","ungezogen","unglaublich","unglaubliches","uninteressiert","unkontrollierbar","unkonventionell","unlimitiert","unpenetrierbar","unschuldig","unsicher","unstabil","unter verschluss","untergrund","unterhaltsam","unterstutz","unterstutzend","unubertroffen","unvergesslich","unverneinbar","unvoreingenommen","unwiderstehlich","unwirtlich","unzensiert","unzuverlassig","up-selling","vaporisieren","verangstigt","verantwortlich","verargert","verarscht","verbessert","verbluffend","verblufft","verboten","verbreiten","verdachtig","verdammt","verdeckt","vereinfacht","verfuhrend","vergebend","vergessen","vergleich","verhauen","verifizieren","verkommen","verlegen","verletzbar","verletzt","verlockend","verloren","vermasselt","vermeiden","vermogen","vernichten","vernichtend","vernunftig","veroffentlichung","verpassen","verraterisch","verruckt","versagen","verschwitzt","versichert","verspielt","versprechend","versteckt","vertrauenswurdig","vertraulich","vertraumt","verurteilend","verwunderlich","verwundet","verzaubernd","verzweifelt","vierfach","vogelfrei","vollig","vollstandig","vorsicht","vorstellungskraft","vorteil","wachstum","wagemutig","wahnsinn","wahnsinnig","wahrhaftig","wahrheit","wahrheitsgemass","wahrscheinlich","warnung","was dir keiner sagt","wehleidig","welt","wenig bekannt","wert","wertvoll","wichtig","widerlich","wiedererkannt","wild","wilde","wilden","willensstarke","wirr","wohltatigkeit","wortlich","wunder","wunderbar","wunderbaren","wunderschon","wutend","zeichen","zeitig","zen","zensiert","zerschlagen","zerschmetternd","zerstorend","zertifiziert","zielorientiert","zischend","zischt","zocken","zogernd","zugeben","zuruckgehalten","zuruckgelassen","zuruckweisen","zusatzlich","zutaten","zuverlassig","zwangsernahrt","zweifelnd","zwickend","zwingend","einfache","einfachen","einfaches","einfacher","simple","simplen","simples","simpler","besten","bestes","bester","beste","bestbewertet","bestbewerteten","bestbewertete","bestbewerteter","bestbewertetes","\u00fcberraschende","\u00fcberraschenden","\u00fcberraschendes","\u00fcberraschender","hilfreiche","hilfreiches","hilfreichen","hilfreicher","f\u00f6rdern","unterst\u00fctzen","helfen","spielerisch","spannende","spannendes","spannenden","spannender","gro\u00dfartige","gro\u00dfartiges","gro\u00dfartigen","gro\u00dfartiger","ideal","ideales","idealen","idealer","faszinierend","faszinierendes","faszinierenden","faszinierender","wichtig","wichtige","wichtiges","wichtigen","wichtiger","sicher","sichere","sicheres","sicheren","sicherer","umfassende","umfassendes","umfassenden","umfassender","ultimative","ultimatives","ultimativen","ultimativer","einzigartige","einzigartiges","einzigartigen","einzigartiger"],"diacritics":true,"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasBreadcrumb":false,"serpData":{"title":"%sitename% %page% %sep% %sitedesc%","description":"","titleTemplate":"%sitename% %page% %sep% %sitedesc%","descriptionTemplate":"","focusKeywords":"","breadcrumbTitle":"Home","robots":{"index":true},"advancedRobots":[],"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":""}}},"tocTitle":"Table of Contents","tocExcludeHeadings":[],"listStyle":"ul"},"_links":{"self":[{"href":"https:\/\/sfentoni-cave.com\/de\/wp-json\/wp\/v2\/pages\/2769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sfentoni-cave.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sfentoni-cave.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sfentoni-cave.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sfentoni-cave.com\/de\/wp-json\/wp\/v2\/comments?post=2769"}],"version-history":[{"count":6,"href":"https:\/\/sfentoni-cave.com\/de\/wp-json\/wp\/v2\/pages\/2769\/revisions"}],"predecessor-version":[{"id":3183,"href":"https:\/\/sfentoni-cave.com\/de\/wp-json\/wp\/v2\/pages\/2769\/revisions\/3183"}],"wp:attachment":[{"href":"https:\/\/sfentoni-cave.com\/de\/wp-json\/wp\/v2\/media?parent=2769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}